{"id":3875,"date":"2025-02-19T17:30:11","date_gmt":"2025-02-19T16:30:11","guid":{"rendered":"http:\/\/volumec.com\/ausbalanciertes-gelenkarm-system\/eat-3\/"},"modified":"2025-10-27T13:03:27","modified_gmt":"2025-10-27T12:03:27","slug":"eat-3","status":"publish","type":"page","link":"https:\/\/volumec.com\/de\/ausbalanciertes-gelenkarm-system\/eat-3\/","title":{"rendered":"EAT 3"},"content":{"rendered":"<div class=\"wpb-content-wrapper\">[vc_row full_width=&#8220;stretch_row&#8220; css=&#8220;.vc_custom_1741128562174{padding-top: 70px !important;padding-bottom: 70px !important;background: #13212E url(http:\/\/volumec.com\/wp-content\/uploads\/2024\/12\/Be-innovative.jpg?id=277) !important;}&#8220;][vc_column][vc_column_text css=&#8220;&#8220; text_align=&#8220;center&#8220; color=&#8220;#ffffff&#8220;]\n<h1>EAT 3<\/h1>\n[\/vc_column_text]<style>.vcex-breadcrumbs.vcex_6a57e677359c9 .sep{color:#ffffff;}.vcex-breadcrumbs.vcex_6a57e677359c9{text-align:center;color:#ffffff;--wpex-link-color:#ffffff;}<\/style><nav class=\"vcex-breadcrumbs vcex-breadcrumbs--links-inherit-color vcex-breadcrumbs--custom-color vcex_6a57e677359c9\"><span><span><a href=\"https:\/\/volumec.com\/de\/\">Home<\/a><\/span><\/span><\/nav>[\/vc_column][\/vc_row][vc_row full_width=&#8220;stretch_row&#8220; el_class=&#8220;ptd80 pbd80 ptm40 pbm40&#8243;][vc_column width=&#8220;1\/2&#8243;][vc_column_text css=&#8220;&#8220; text_transform=&#8220;uppercase&#8220;]\n<h2><strong>Ausbalancierter Gelenkarm<br \/>\n<\/strong><\/h2>\n[\/vc_column_text][vc_column_text css=&#8220;&#8220; el_class=&#8220;mtd50 mtm40 mbd40 mbm30&#8243;]Der dreifach schwenkbare Arm EAT3 erm\u00f6glicht es Ihnen, schwere Werkzeuge auszubalancieren und hohe Arbeitsdrehmomente zu bew\u00e4ltigen.[\/vc_column_text]<div class=\"cq-datatable   cq-datatable-medium cq-datatable-gray\"><div class=\"cq-datatable-row cq-datatable-header cq-datatable-bg-customized\" style=\"background:#121A1E\"><div class=\"cq-datatable-cell\" data-title=\"Arbeitsradius\"> Arbeitsradius <\/div><div class=\"cq-datatable-cell\" data-title=\"Vertikales Laufen\"> Vertikales Laufen <\/div><div class=\"cq-datatable-cell\" data-title=\"Drehung\"> Drehung <\/div><div class=\"cq-datatable-cell\" data-title=\"Gewicht Arm\"> Gewicht Arm <\/div><\/div><div class=\"cq-datatable-row cq-datatable-data\"><div class=\"cq-datatable-cell\"> 1650 mm + Kopf <\/div><div class=\"cq-datatable-cell\"> 900 mm <\/div><div class=\"cq-datatable-cell\"> 360 \u00b0 <\/div><div class=\"cq-datatable-cell\"> 62 kg <\/div><\/div><div class=\"cq-datatable-row cq-datatable-data\"><div class=\"cq-datatable-cell\"> 65 in + Kopf <\/div><div class=\"cq-datatable-cell\"> 35 in <\/div><div class=\"cq-datatable-cell\"> 360 \u00b0 <\/div><div class=\"cq-datatable-cell\"> 137 lbs <\/div><\/div>\n<\/div>[vc_row_inner][vc_column_inner width=&#8220;1\/3&#8243;][vc_column_text css=&#8220;&#8220; text_align=&#8220;center&#8220; el_class=&#8220;testata_fake_tabella&#8220; color=&#8220;#ffffff&#8220; font_size=&#8220;18px&#8220; font_family=&#8220;Manrope&#8220; line_height=&#8220;22px&#8220; font_weight=&#8220;400&#8243;]Kompatible Kopfzeilen[\/vc_column_text][vc_column_text css=&#8220;.vc_custom_1743504751110{margin-top: 10px !important;}&#8220; text_align=&#8220;center&#8220;]Alle EAT-Serien werden mit einer festen Kopfleiste geliefert.[\/vc_column_text][\/vc_column_inner][vc_column_inner el_class=&#8220;mtm20&#8243; width=&#8220;1\/3&#8243;][vc_column_text css=&#8220;&#8220; text_align=&#8220;center&#8220; el_class=&#8220;testata_fake_tabella&#8220; color=&#8220;#ffffff&#8220; font_size=&#8220;18px&#8220; font_family=&#8220;Manrope&#8220; line_height=&#8220;22px&#8220; font_weight=&#8220;400&#8243;]BANKBEFESTIGUNG (standard)[\/vc_column_text]<figure class=\"vcex-image vcex-module wpex-text-center\"><div class=\"vcex-image-inner wpex-relative wpex-inline-block vc_custom_1739981617333\"><img width=\"200\" height=\"200\" src=\"https:\/\/volumec.com\/wp-content\/uploads\/2025\/02\/fb-ea1.png\" class=\"vcex-image-img wpex-align-middle\" alt=\"\" loading=\"lazy\" decoding=\"async\" srcset=\"https:\/\/volumec.com\/wp-content\/uploads\/2025\/02\/fb-ea1.png 200w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/02\/fb-ea1-150x150.png 150w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/02\/fb-ea1-100x100.png 100w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" \/><\/div><\/figure>[\/vc_column_inner][vc_column_inner el_class=&#8220;mtm20&#8243; width=&#8220;1\/3&#8243;][vc_column_text css=&#8220;&#8220; text_align=&#8220;center&#8220; el_class=&#8220;testata_fake_tabella&#8220; color=&#8220;#ffffff&#8220; font_size=&#8220;18px&#8220; font_family=&#8220;Manrope&#8220; line_height=&#8220;22px&#8220; font_weight=&#8220;400&#8243;]FISSAGGIO A SOFFITTO Versione (S)[\/vc_column_text][vc_column_text css=&#8220;.vc_custom_1743504787778{margin-top: 10px !important;}&#8220; text_align=&#8220;center&#8220;]NIEN[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][vc_column width=&#8220;1\/2&#8243; el_class=&#8220;mtm20&#8243;]<div class=\"wpex-slider-preloaderimg wpex-relative\"><img width=\"800\" height=\"800\" src=\"https:\/\/volumec.com\/wp-content\/uploads\/2025\/10\/Ausbalanciertes-Gelenkarm-System-EAT-3-01.png\" class=\"skip-lazy\" alt=\"\" data-no-lazy=\"1\" srcset=\"https:\/\/volumec.com\/wp-content\/uploads\/2025\/10\/Ausbalanciertes-Gelenkarm-System-EAT-3-01.png 800w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/10\/Ausbalanciertes-Gelenkarm-System-EAT-3-01-300x300.png 300w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/10\/Ausbalanciertes-Gelenkarm-System-EAT-3-01-150x150.png 150w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/10\/Ausbalanciertes-Gelenkarm-System-EAT-3-01-768x768.png 768w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/10\/Ausbalanciertes-Gelenkarm-System-EAT-3-01-600x600.png 600w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/10\/Ausbalanciertes-Gelenkarm-System-EAT-3-01-100x100.png 100w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/10\/Ausbalanciertes-Gelenkarm-System-EAT-3-01-460x460.png 460w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/div><div class=\"vcex-image-slider vcex-module wpex-slider slider-pro wpex-clr\" data-loop=\"true\" data-auto-play-delay=\"5000\" data-animation-speed=\"600\" data-height-animation-duration=\"500\" data-thumbnail-height=\"70\" data-thumbnail-width=\"70\" data-reach-video-action=\"none\"><div class=\"wpex-slider-slides sp-slides\"><div class=\"wpex-slider-slide sp-slide\"><div class=\"wpex-slider-media wpex-relative\"><img width=\"800\" height=\"800\" src=\"https:\/\/volumec.com\/wp-content\/uploads\/2025\/10\/Ausbalanciertes-Gelenkarm-System-EAT-3-01.png\" class=\"skip-lazy\" alt=\"\" data-no-lazy=\"1\" srcset=\"https:\/\/volumec.com\/wp-content\/uploads\/2025\/10\/Ausbalanciertes-Gelenkarm-System-EAT-3-01.png 800w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/10\/Ausbalanciertes-Gelenkarm-System-EAT-3-01-300x300.png 300w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/10\/Ausbalanciertes-Gelenkarm-System-EAT-3-01-150x150.png 150w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/10\/Ausbalanciertes-Gelenkarm-System-EAT-3-01-768x768.png 768w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/10\/Ausbalanciertes-Gelenkarm-System-EAT-3-01-600x600.png 600w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/10\/Ausbalanciertes-Gelenkarm-System-EAT-3-01-100x100.png 100w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/10\/Ausbalanciertes-Gelenkarm-System-EAT-3-01-460x460.png 460w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/div><\/div><div class=\"wpex-slider-slide sp-slide\"><div class=\"wpex-slider-media wpex-relative\"><img width=\"800\" height=\"800\" src=\"https:\/\/volumec.com\/wp-content\/uploads\/2025\/10\/Ausbalanciertes-Gelenkarm-System-EAT-3-02.png\" class=\"skip-lazy\" alt=\"\" data-no-lazy=\"1\" srcset=\"https:\/\/volumec.com\/wp-content\/uploads\/2025\/10\/Ausbalanciertes-Gelenkarm-System-EAT-3-02.png 800w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/10\/Ausbalanciertes-Gelenkarm-System-EAT-3-02-300x300.png 300w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/10\/Ausbalanciertes-Gelenkarm-System-EAT-3-02-150x150.png 150w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/10\/Ausbalanciertes-Gelenkarm-System-EAT-3-02-768x768.png 768w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/10\/Ausbalanciertes-Gelenkarm-System-EAT-3-02-600x600.png 600w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/10\/Ausbalanciertes-Gelenkarm-System-EAT-3-02-100x100.png 100w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/10\/Ausbalanciertes-Gelenkarm-System-EAT-3-02-460x460.png 460w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/div><\/div><\/div><\/div>[\/vc_column][\/vc_row][vc_row full_width=&#8220;stretch_row&#8220; content_placement=&#8220;middle&#8220; el_class=&#8220;ptd70 pbd50 ptm50 pbm50&#8243; css=&#8220;.vc_custom_1734433172112{background-color: #131A1F !important;}&#8220;][vc_column css_animation=&#8220;fadeInLeft&#8220;][vc_column_text css=&#8220;&#8220; color=&#8220;#0c8df2&#8243; font_size=&#8220;19px&#8220; text_align=&#8220;center&#8220; font_weight=&#8220;700&#8243;]Die Einf\u00fchrung der EASYARM-Arme erm\u00f6glicht es schlie\u00dflich, die Anforderungen der TU 81\/2008 (insbesondere der Artikel 168 und 203) zu erf\u00fcllen.[\/vc_column_text][vc_column_text css=&#8220;&#8220; el_class=&#8220;mtd30 mtm30&#8243; text_align=&#8220;center&#8220; color=&#8220;#ffffff&#8220;]\n<p class=\"\" data-start=\"42\" data-end=\"764\">Art. 168 Der Arbeitgeber trifft die erforderlichen organisatorischen Ma\u00dfnahmen und setzt geeignete Mittel, insbesondere mechanische Ausstattungen, ein, um die Notwendigkeit der manuellen Handhabung von Lasten durch die Arbeitnehmer zu vermeiden. Wenn die manuelle Handhabung von Lasten durch die Arbeitnehmer nicht vermieden werden kann, trifft der Arbeitgeber die erforderlichen organisatorischen Ma\u00dfnahmen, setzt geeignete Mittel ein und stellt den Arbeitnehmern die geeigneten Hilfsmittel zur Verf\u00fcgung, um das Risiko der manuellen Handhabung dieser Lasten zu verringern [\u2026]\n<p class=\"\" data-start=\"766\" data-end=\"1336\">Art. 203 [\u2026] Der Arbeitgeber erstellt und wendet ein Programm technischer oder organisatorischer Ma\u00dfnahmen an, das darauf abzielt, die Exposition und die Risiken auf ein Minimum zu reduzieren [\u2026], wobei insbesondere Folgendes ber\u00fccksichtigt wird: a) andere Arbeitsmethoden, die eine geringere Exposition gegen\u00fcber mechanischen Vibrationen erfordern; b) die Auswahl geeigneter Arbeitsmittel, die unter Ber\u00fccksichtigung der ergonomischen Prinzipien entworfen wurden und unter Ber\u00fccksichtigung der auszuf\u00fchrenden Arbeit das geringstm\u00f6gliche Ma\u00df an Vibrationen erzeugen [\u2026]\n[\/vc_column_text][\/vc_column][\/vc_row][vc_row el_class=&#8220;mtd20 mtm20&#8243; css=&#8220;.vc_custom_1741446916556{margin-top: 50px !important;margin-bottom: 50px !important;}&#8220;][vc_column width=&#8220;1\/4&#8243; el_class=&#8220;cd cm&#8220;][\/vc_column][vc_column width=&#8220;1\/4&#8243; el_class=&#8220;popmake-7008&#8243;]<style>.vcex-button.vcex_6a57e67742fa6{border-radius:0px;color:#000000!important;padding:20px;border:2px solid #FE0100;font-family:Manrope;font-size:16px;font-weight:700;}.vcex-button.vcex_6a57e67742fa6:hover{color:#000000!important;}<\/style><a href=\"#\" class=\"vcex-button theme-button outline inline bottone1 bottone_rosso vcex_6a57e67742fa6\"><span class=\"vcex-button-inner theme-button-inner wpex-flex wpex-flex-wrap wpex-items-center wpex-justify-center\">ENTLADEN DIE BROSCH\u00dcRE<span class=\"vcex-button-icon vcex-icon-wrap theme-button-icon-right\"><span aria-hidden=\"true\" class=\"fas fa-arrow-right\"><\/span><\/span><\/span><\/a> [\/vc_column][vc_column width=&#8220;1\/4&#8243;]<style>.vcex-button.vcex_6a57e67745c97{border-radius:0px;color:#000000!important;padding:20px;border:2px solid #0b8df1;font-family:Manrope;font-size:16px;font-weight:700;}.vcex-button.vcex_6a57e67745c97:hover{color:#000000!important;}<\/style><div class=\"theme-button-wrap textcenter wpex-clr\"><a href=\"http:\/\/volumec.com\/de\/fragen-sie-uns-an\/\" class=\"vcex-button theme-button outline align-center inline bottone1 mtd30 mtm30 vcex_6a57e67745c97\"><span class=\"vcex-button-inner theme-button-inner wpex-flex wpex-flex-wrap wpex-items-center wpex-justify-center\">FRAGEN SIE UNS AN<span class=\"vcex-button-icon vcex-icon-wrap theme-button-icon-right\"><span aria-hidden=\"true\" class=\"fas fa-arrow-right\"><\/span><\/span><\/span><\/a><\/div> [\/vc_column][vc_column width=&#8220;1\/4&#8243;][\/vc_column][\/vc_row][vc_row full_width=&#8220;stretch_row&#8220; local_scroll_id=&#8220;info&#8220; css=&#8220;.vc_custom_1737457059910{background-color: #F1F1F1 !important;}&#8220; el_class=&#8220;ptd50 ptm50 pbd50 pbm50 mtd20 mtm20&#8243;][vc_column width=&#8220;1\/2&#8243;][vc_column_text css=&#8220;&#8220;]\n<h2 style=\"text-align: center;\"><strong>Vorteile<\/strong><\/h2>\n[\/vc_column_text]<style>.vcex-icon-box.vcex_6a57e6774b24e .vcex-icon-box-heading{margin-bottom:0px;font-weight:700;}<\/style><div class=\"vcex-module vcex-icon-box vcex-icon-box-one wpex-flex wpex-items-center wpex-text-left mtd30 mbd30 mtm20 mbm20 vcex_6a57e6774b24e\"><div class=\"vcex-icon-box-symbol vcex-icon-box-symbol--icon wpex-flex-shrink-0 wpex-mr-25\"><div class=\"vcex-icon-box-icon wpex-items-center wpex-justify-center wpex-child-inherit-color wpex-text-center wpex-leading-none wpex-flex wpex-text-1\"><span class=\"fa-light fa-arrow-down-right\" aria-hidden=\"true\"><\/span><\/div><\/div><div class=\"vcex-icon-box-text wpex-flex-grow\"><div class=\"vcex-icon-box-content wpex-last-mb-0 wpex-clr\"><p class=\"text-justify\"><i class=\"fas fa-caret-right mr-2\"><\/i>Befreien Sie Ihr Werkzeug vom Gewicht, reduzieren Sie die Erm\u00fcdung des Bedieners, sch\u00fctzen Sie die Gesundheit und steigern Sie die Produktivit\u00e4t.<\/p>\n<\/div><\/div><\/div><style>.vcex-icon-box.vcex_6a57e6774e012 .vcex-icon-box-heading{margin-bottom:0px;font-weight:700;}<\/style><div class=\"vcex-module vcex-icon-box vcex-icon-box-one wpex-flex wpex-items-center wpex-text-left mtd30 mbd30 mtm20 mbm20 vcex_6a57e6774e012\"><div class=\"vcex-icon-box-symbol vcex-icon-box-symbol--icon wpex-flex-shrink-0 wpex-mr-25\"><div class=\"vcex-icon-box-icon wpex-items-center wpex-justify-center wpex-child-inherit-color wpex-text-center wpex-leading-none wpex-flex wpex-text-1\"><span class=\"fa-light fa-arrow-down-right\" aria-hidden=\"true\"><\/span><\/div><\/div><div class=\"vcex-icon-box-text wpex-flex-grow\"><div class=\"vcex-icon-box-content wpex-last-mb-0 wpex-clr\"><p class=\"text-justify\"><i class=\"fas fa-caret-right mr-2\"><\/i>Erm\u00f6glicht eine reibungslose und einfache Bewegung in jede Richtung.<\/p>\n<\/div><\/div><\/div><style>.vcex-icon-box.vcex_6a57e67750c83 .vcex-icon-box-heading{margin-bottom:0px;font-weight:700;}<\/style><div class=\"vcex-module vcex-icon-box vcex-icon-box-one wpex-flex wpex-items-center wpex-text-left mtd30 mbd30 mtm20 mbm20 vcex_6a57e67750c83\"><div class=\"vcex-icon-box-symbol vcex-icon-box-symbol--icon wpex-flex-shrink-0 wpex-mr-25\"><div class=\"vcex-icon-box-icon wpex-items-center wpex-justify-center wpex-child-inherit-color wpex-text-center wpex-leading-none wpex-flex wpex-text-1\"><span class=\"fa-light fa-arrow-down-right\" aria-hidden=\"true\"><\/span><\/div><\/div><div class=\"vcex-icon-box-text wpex-flex-grow\"><div class=\"vcex-icon-box-content wpex-last-mb-0 wpex-clr\"><p class=\"text-justify\"><i class=\"fas fa-caret-right mr-2\"><\/i>Nimmt das durch den Werkzeuggebrauch entstehende Drehmoment und die Torsion auf.<\/p>\n<\/div><\/div><\/div><style>.vcex-icon-box.vcex_6a57e67753947 .vcex-icon-box-heading{margin-bottom:0px;font-weight:700;}<\/style><div class=\"vcex-module vcex-icon-box vcex-icon-box-one wpex-flex wpex-items-center wpex-text-left mtd30 mbd30 mtm20 mbm20 vcex_6a57e67753947\"><div class=\"vcex-icon-box-symbol vcex-icon-box-symbol--icon wpex-flex-shrink-0 wpex-mr-25\"><div class=\"vcex-icon-box-icon wpex-items-center wpex-justify-center wpex-child-inherit-color wpex-text-center wpex-leading-none wpex-flex wpex-text-1\"><span class=\"fa-light fa-arrow-down-right\" aria-hidden=\"true\"><\/span><\/div><\/div><div class=\"vcex-icon-box-text wpex-flex-grow\"><div class=\"vcex-icon-box-content wpex-last-mb-0 wpex-clr\"><p class=\"text-justify\"><i class=\"fas fa-caret-right mr-2\"><\/i>Komplett bei unserem Unternehmen in Italien hergestellt.<\/p>\n<\/div><\/div><\/div><style>.vcex-icon-box.vcex_6a57e6775662d .vcex-icon-box-heading{margin-bottom:0px;font-weight:700;}<\/style><div class=\"vcex-module vcex-icon-box vcex-icon-box-one wpex-flex wpex-items-center wpex-text-left mtd30 mbd30 mtm20 mbm20 vcex_6a57e6775662d\"><div class=\"vcex-icon-box-symbol vcex-icon-box-symbol--icon wpex-flex-shrink-0 wpex-mr-25\"><div class=\"vcex-icon-box-icon wpex-items-center wpex-justify-center wpex-child-inherit-color wpex-text-center wpex-leading-none wpex-flex wpex-text-1\"><span class=\"fa-light fa-arrow-down-right\" aria-hidden=\"true\"><\/span><\/div><\/div><div class=\"vcex-icon-box-text wpex-flex-grow\"><div class=\"vcex-icon-box-content wpex-last-mb-0 wpex-clr\"><p class=\"text-justify\"><i class=\"fas fa-caret-right mr-2\"><\/i>Bietet eine vollst\u00e4ndige Palette von L\u00f6sungen, die f\u00fcr jede Aufgabe geeignet sind.<\/p>\n<\/div><\/div><\/div>[\/vc_column][vc_column width=&#8220;1\/2&#8243; el_class=&#8220;mtm40&#8243;][vc_column_text css=&#8220;&#8220;]\n<h2 style=\"text-align: center;\"><strong>Arbeitsbereich<\/strong><\/h2>\n[\/vc_column_text]<figure class=\"vcex-image vcex-module\"><div class=\"vcex-image-inner wpex-relative wpex-inline-block vc_custom_1744968473512\"><a href=\"https:\/\/volumec.com\/wp-content\/uploads\/2025\/04\/EAT16100XXwork-area-1-3-pdf.jpg\" class=\"wpex-lightbox\"><img width=\"1497\" height=\"1058\" src=\"https:\/\/volumec.com\/wp-content\/uploads\/2025\/04\/EAT16100XXwork-area-1-3-pdf.jpg\" class=\"vcex-image-img wpex-align-middle\" alt=\"\" loading=\"lazy\" decoding=\"async\" \/><\/a><\/div><\/figure>[\/vc_column][\/vc_row][vc_row el_class=&#8220;mtd70 mtm50&#8243;][vc_column][vc_column_text css=&#8220;&#8220;]\n<h2><strong>EAT3<\/strong> &#8211; Standard Triple Gelenkarm<\/h2>\n[\/vc_column_text][vc_column_text css=&#8220;&#8220; el_class=&#8220;mtd20 mtm20 mbd20 mbm20&#8243;]Il braccio articolato EA3 bilancia il peso dell&#8217;attrezzo o dell&#8216; utensile in tutta l&#8217;area di lavoro, garantendo movimenti rapidi e precisi senza sforzo. ZERO GRAVITY.[\/vc_column_text][\/vc_column][\/vc_row][vc_row el_class=&#8220;mtd40 mtm30&#8243;][vc_column width=&#8220;1\/2&#8243;]<div class=\"cq-datatable   cq-datatable-medium cq-datatable-gray\"><div class=\"cq-datatable-row cq-datatable-header cq-datatable-bg-customized\" style=\"background:#121A1E\"><div class=\"cq-datatable-cell\" data-title=\"Modell\"> Modell <\/div><div class=\"cq-datatable-cell\" data-title=\"Drehmoment (Nm)\"> Drehmoment (Nm) <\/div><div class=\"cq-datatable-cell\" data-title=\"Gewicht Arm (kg)\"> Gewicht Arm (kg) <\/div><\/div><div class=\"cq-datatable-row cq-datatable-data\"><div class=\"cq-datatable-cell\"> EAT1610014 <\/div><div class=\"cq-datatable-cell\"> 300 <\/div><div class=\"cq-datatable-cell\"> 8 - 14 <\/div><\/div><div class=\"cq-datatable-row cq-datatable-data\"><div class=\"cq-datatable-cell\"> EAT1610019 <\/div><div class=\"cq-datatable-cell\"> 500 <\/div><div class=\"cq-datatable-cell\"> 15 - 19 <\/div><\/div><div class=\"cq-datatable-row cq-datatable-data\"><div class=\"cq-datatable-cell\"> EAT1610025 <\/div><div class=\"cq-datatable-cell\"> 500 <\/div><div class=\"cq-datatable-cell\"> 20 - 25 <\/div><\/div><div class=\"cq-datatable-row cq-datatable-data\"><div class=\"cq-datatable-cell\"> EAT1610030 <\/div><div class=\"cq-datatable-cell\"> 500 <\/div><div class=\"cq-datatable-cell\"> 26 - 30 <\/div><\/div><div class=\"cq-datatable-row cq-datatable-data\"><div class=\"cq-datatable-cell\"> EAT1610035 <\/div><div class=\"cq-datatable-cell\"> 500 <\/div><div class=\"cq-datatable-cell\"> 31 - 35 <\/div><\/div><div class=\"cq-datatable-row cq-datatable-data\"><div class=\"cq-datatable-cell\"> EAT1610040 <\/div><div class=\"cq-datatable-cell\"> 500 <\/div><div class=\"cq-datatable-cell\"> 36 - 40 <\/div><\/div>\n<\/div>[\/vc_column][vc_column width=&#8220;1\/2&#8243;][\/vc_column][\/vc_row][vc_row el_class=&#8220;mtd70 mtm50&#8243;][vc_column][vc_column_text css=&#8220;&#8220;]\n<h2 style=\"text-align: center;\"><b>WERKZEUGK\u00d6PFE und ORBITALSCHL\u00c4GE<br \/>\n<\/b><\/h2>\n[\/vc_column_text][\/vc_column][\/vc_row][vc_row el_class=&#8220;ptd50 ptm50&#8243;][vc_column width=&#8220;1\/3&#8243;]<style>.vcex-image.vcex_6a57e67759f59 .vcex-image-img{border-radius:0px;border-color:#00000042;}<\/style><figure class=\"vcex-image vcex-module wpex-text-center vcex_6a57e67759f59\"><div class=\"vcex-image-inner wpex-relative wpex-inline-block\"><a href=\"https:\/\/volumec.com\/wp-content\/uploads\/2025\/02\/T40-T60-T80-1.jpg\" class=\"wpex-lightbox\"><img width=\"800\" height=\"400\" src=\"https:\/\/volumec.com\/wp-content\/uploads\/2025\/02\/T40-T60-T80-1.jpg\" class=\"vcex-image-img wpex-align-middle wpex-border wpex-border-solid\" alt=\"\" loading=\"lazy\" decoding=\"async\" srcset=\"https:\/\/volumec.com\/wp-content\/uploads\/2025\/02\/T40-T60-T80-1.jpg 800w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/02\/T40-T60-T80-1-300x150.jpg 300w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/02\/T40-T60-T80-1-768x384.jpg 768w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/02\/T40-T60-T80-1-600x300.jpg 600w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/div><\/figure>[vc_column_text css=&#8220;&#8220; font_size=&#8220;19px&#8220; line_height=&#8220;100%&#8220; font_weight=&#8220;700&#8243; el_class=&#8220;mtd20 mtm20&#8243;]\n<p class=\"mb-2\">T40-T60-T80 (werkzeugk\u00f6pfe)<\/p>\n[\/vc_column_text][vc_column_text css=&#8220;&#8220; el_class=&#8220;mtd15 mtm15&#8243;]Klemme f\u00fcr Werkzeugbefestigung &#8211; Durchmesser 40 &#8211; 60 &#8211; 80 mm[\/vc_column_text][\/vc_column][vc_column width=&#8220;1\/3&#8243; el_class=&#8220;mtm40&#8243;]<style>.vcex-image.vcex_6a57e6775bc87 .vcex-image-img{border-radius:0px;border-color:#00000042;}<\/style><figure class=\"vcex-image vcex-module wpex-text-center vcex_6a57e6775bc87\"><div class=\"vcex-image-inner wpex-relative wpex-inline-block\"><a href=\"https:\/\/volumec.com\/wp-content\/uploads\/2025\/02\/A40-A60-A80-1.jpg\" class=\"wpex-lightbox\"><img width=\"800\" height=\"400\" src=\"https:\/\/volumec.com\/wp-content\/uploads\/2025\/02\/A40-A60-A80-1.jpg\" class=\"vcex-image-img wpex-align-middle wpex-border wpex-border-solid\" alt=\"\" loading=\"lazy\" decoding=\"async\" srcset=\"https:\/\/volumec.com\/wp-content\/uploads\/2025\/02\/A40-A60-A80-1.jpg 800w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/02\/A40-A60-A80-1-300x150.jpg 300w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/02\/A40-A60-A80-1-768x384.jpg 768w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/02\/A40-A60-A80-1-600x300.jpg 600w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/div><\/figure>[vc_column_text css=&#8220;&#8220; font_size=&#8220;19px&#8220; line_height=&#8220;100%&#8220; font_weight=&#8220;700&#8243; el_class=&#8220;mtd20 mtm20&#8243;]\n<p class=\"mb-2\">A40-A60-A80 (werkzeugk\u00f6pfe)<\/p>\n[\/vc_column_text][vc_column_text css=&#8220;&#8220; el_class=&#8220;mtd15 mtm15&#8243;]Adapter f\u00fcr Durchmesser unter 40-60-80 mm[\/vc_column_text][\/vc_column][vc_column width=&#8220;1\/3&#8243;]<style>.vcex-image.vcex_6a57e6775d962 .vcex-image-img{border-radius:0px;border-color:#00000042;}<\/style><figure class=\"vcex-image vcex-module wpex-text-center vcex_6a57e6775d962\"><div class=\"vcex-image-inner wpex-relative wpex-inline-block\"><a href=\"https:\/\/volumec.com\/wp-content\/uploads\/2025\/04\/SRH-C2.jpg\" class=\"wpex-lightbox\"><img width=\"1920\" height=\"915\" src=\"https:\/\/volumec.com\/wp-content\/uploads\/2025\/04\/SRH-C2.jpg\" class=\"vcex-image-img wpex-align-middle wpex-border wpex-border-solid\" alt=\"\" loading=\"lazy\" decoding=\"async\" srcset=\"https:\/\/volumec.com\/wp-content\/uploads\/2025\/04\/SRH-C2.jpg 1920w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/04\/SRH-C2-300x143.jpg 300w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/04\/SRH-C2-1024x488.jpg 1024w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/04\/SRH-C2-768x366.jpg 768w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/04\/SRH-C2-1536x732.jpg 1536w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/04\/SRH-C2-600x286.jpg 600w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/><\/a><\/div><\/figure>[vc_column_text css=&#8220;&#8220; font_size=&#8220;19px&#8220; line_height=&#8220;100%&#8220; font_weight=&#8220;700&#8243; el_class=&#8220;mtd20 mtm20&#8243;]\n<p class=\"mb-2\">SRH &#8211; C2 (orbitalschl\u00e4ge)<\/p>\n[\/vc_column_text][vc_column_text css=&#8220;&#8220; el_class=&#8220;mtd15 mtm15&#8243;]Verst\u00e4rkter Orbitalaufsatz \u2013 max. Durchmesser 125 mm[\/vc_column_text][\/vc_column][\/vc_row][vc_row full_width=&#8220;stretch_row&#8220; local_scroll_id=&#8220;info&#8220; css=&#8220;.vc_custom_1740392980023{margin-bottom: -35px !important;background-color: #F1F1F1 !important;}&#8220; el_class=&#8220;ptd50 ptm50 pbd50 pbm50&#8243;][vc_column][vc_column_text css=&#8220;&#8220;]\n<h2 style=\"text-align: center;\"><strong>OPTIONAL<\/strong><\/h2>\n[\/vc_column_text][\/vc_column][\/vc_row][vc_row full_width=&#8220;stretch_row&#8220; el_class=&#8220;ptd40 mtm40&#8243; css=&#8220;.vc_custom_1740391977983{background-color: #F1F1F1 !important;}&#8220;][vc_column width=&#8220;1\/4&#8243;]<style>.vcex-image.vcex_6a57e6775f660 .vcex-image-img{border-radius:0px;border-color:#00000042;}<\/style><figure class=\"vcex-image vcex-module wpex-text-center vcex_6a57e6775f660\"><div class=\"vcex-image-inner wpex-relative wpex-inline-block\"><a href=\"https:\/\/volumec.com\/wp-content\/uploads\/2025\/02\/ccf100-eam.jpg\" class=\"wpex-lightbox\"><img width=\"800\" height=\"800\" src=\"https:\/\/volumec.com\/wp-content\/uploads\/2025\/02\/ccf100-eam.jpg\" class=\"vcex-image-img wpex-align-middle wpex-border wpex-border-solid\" alt=\"\" loading=\"lazy\" decoding=\"async\" srcset=\"https:\/\/volumec.com\/wp-content\/uploads\/2025\/02\/ccf100-eam.jpg 800w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/02\/ccf100-eam-300x300.jpg 300w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/02\/ccf100-eam-150x150.jpg 150w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/02\/ccf100-eam-768x768.jpg 768w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/02\/ccf100-eam-600x600.jpg 600w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/02\/ccf100-eam-100x100.jpg 100w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/02\/ccf100-eam-460x460.jpg 460w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/div><\/figure>[vc_column_text css=&#8220;&#8220; font_size=&#8220;19px&#8220; line_height=&#8220;100%&#8220; font_weight=&#8220;700&#8243; el_class=&#8220;mtd20 mtm20&#8243;](CCF100-EAM) TROLLEY 800X800 mm[\/vc_column_text][vc_column_text css=&#8220;&#8220; el_class=&#8220;mtd15 mtm15&#8243; font_size=&#8220;13px&#8220;]Mit 30-mm-Sockel, zentraler Arms\u00e4ule mit verstellbarer H\u00f6he von 650 mm bis 1050 mm, 4 drehbaren R\u00e4dern, 2 mit Bremsen.<br \/>\nGewicht 185 kg<br \/>\n(Niedrige R\u00e4der)[\/vc_column_text][\/vc_column][vc_column width=&#8220;1\/4&#8243; el_class=&#8220;mtm40&#8243;]<style>.vcex-image.vcex_6a57e6776132e .vcex-image-img{border-radius:0px;border-color:#00000042;}<\/style><figure class=\"vcex-image vcex-module wpex-text-center vcex_6a57e6776132e\"><div class=\"vcex-image-inner wpex-relative wpex-inline-block\"><a href=\"https:\/\/volumec.com\/wp-content\/uploads\/2025\/05\/CCM100-EAM.png\" class=\"wpex-lightbox\"><img width=\"800\" height=\"800\" src=\"https:\/\/volumec.com\/wp-content\/uploads\/2025\/05\/CCM100-EAM.png\" class=\"vcex-image-img wpex-align-middle wpex-border wpex-border-solid\" alt=\"\" loading=\"lazy\" decoding=\"async\" srcset=\"https:\/\/volumec.com\/wp-content\/uploads\/2025\/05\/CCM100-EAM.png 800w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/05\/CCM100-EAM-300x300.png 300w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/05\/CCM100-EAM-150x150.png 150w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/05\/CCM100-EAM-768x768.png 768w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/05\/CCM100-EAM-600x600.png 600w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/05\/CCM100-EAM-100x100.png 100w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/05\/CCM100-EAM-460x460.png 460w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/div><\/figure>[vc_column_text css=&#8220;&#8220; font_size=&#8220;19px&#8220; line_height=&#8220;100%&#8220; font_weight=&#8220;700&#8243; el_class=&#8220;mtd20 mtm20&#8243;]\n<p class=\"mb-2\">(CCM001-EAM) TROLLEY 800X800X30 mm<\/p>\n[\/vc_column_text][vc_column_text css=&#8220;&#8220; el_class=&#8220;mtd15 mtm15&#8243; font_size=&#8220;13px&#8220;]Komplett mit Hubs\u00e4ulenarm h=1920 mm<br \/>\nBewegung auf Linearf\u00fchrung und Trapezstange mit elektrischer oder pneumatischer Schraubendrehersteuerung Halterungen f\u00fcr 4 drehbare R\u00e4der, 2 mit Bremse<br \/>\nSchiebegriff.<br \/>\nGewicht 240 Kg<br \/>\n(Niedrige R\u00e4der)[\/vc_column_text][\/vc_column][vc_column width=&#8220;1\/4&#8243;]<style>.vcex-image.vcex_6a57e67762fd1 .vcex-image-img{border-radius:0px;border-color:#00000042;}<\/style><figure class=\"vcex-image vcex-module wpex-text-center vcex_6a57e67762fd1\"><div class=\"vcex-image-inner wpex-relative wpex-inline-block\"><a href=\"https:\/\/volumec.com\/wp-content\/uploads\/2025\/02\/cf001.jpg\" class=\"wpex-lightbox\"><img width=\"800\" height=\"800\" src=\"https:\/\/volumec.com\/wp-content\/uploads\/2025\/02\/cf001.jpg\" class=\"vcex-image-img wpex-align-middle wpex-border wpex-border-solid\" alt=\"\" loading=\"lazy\" decoding=\"async\" srcset=\"https:\/\/volumec.com\/wp-content\/uploads\/2025\/02\/cf001.jpg 800w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/02\/cf001-300x300.jpg 300w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/02\/cf001-150x150.jpg 150w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/02\/cf001-768x768.jpg 768w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/02\/cf001-600x600.jpg 600w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/02\/cf001-100x100.jpg 100w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/02\/cf001-460x460.jpg 460w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/div><\/figure>[vc_column_text css=&#8220;&#8220; font_size=&#8220;19px&#8220; line_height=&#8220;100%&#8220; font_weight=&#8220;700&#8243; el_class=&#8220;mtd20 mtm20&#8243;](CF001) HUBS\u00c4ULENARMH=1850 mm[\/vc_column_text][vc_column_text css=&#8220;&#8220; el_class=&#8220;mtd15 mtm15&#8243; font_size=&#8220;13px&#8220;]Bewegung auf Linearf\u00fchrung und Trapezstange, gesteuert mit elektrischem oder pneumatischem Schraubenzieher.<br \/>\nGewicht 60 Kg[\/vc_column_text][\/vc_column][vc_column width=&#8220;1\/4&#8243;]<style>.vcex-image.vcex_6a57e67764d10 .vcex-image-img{border-radius:0px;border-color:#00000042;}<\/style><figure class=\"vcex-image vcex-module wpex-text-center vcex_6a57e67764d10\"><div class=\"vcex-image-inner wpex-relative wpex-inline-block\"><a href=\"https:\/\/volumec.com\/wp-content\/uploads\/2025\/02\/tds2000.jpg\" class=\"wpex-lightbox\"><img width=\"800\" height=\"800\" src=\"https:\/\/volumec.com\/wp-content\/uploads\/2025\/02\/tds2000.jpg\" class=\"vcex-image-img wpex-align-middle wpex-border wpex-border-solid\" alt=\"\" loading=\"lazy\" decoding=\"async\" srcset=\"https:\/\/volumec.com\/wp-content\/uploads\/2025\/02\/tds2000.jpg 800w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/02\/tds2000-300x300.jpg 300w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/02\/tds2000-150x150.jpg 150w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/02\/tds2000-768x768.jpg 768w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/02\/tds2000-600x600.jpg 600w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/02\/tds2000-100x100.jpg 100w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/02\/tds2000-460x460.jpg 460w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/div><\/figure>[vc_column_text css=&#8220;&#8220; font_size=&#8220;19px&#8220; line_height=&#8220;100%&#8220; font_weight=&#8220;700&#8243; el_class=&#8220;mtd20 mtm20&#8243;]\n<p class=\"mb-2\">(TDS2000) LINEARGLEITF\u00dcHRUNG<\/p>\n[\/vc_column_text][vc_column_text css=&#8220;&#8220; el_class=&#8220;mtd15 mtm15&#8243; font_size=&#8220;13px&#8220;]Gesamtl\u00e4nge 2200 mm<br \/>\nArbeitshub 2000 mm mit selbsttragender Struktur und 4 verstellbaren Auslegern.<br \/>\nGewicht: Kg.120[\/vc_column_text][\/vc_column][\/vc_row][vc_row css_animation=&#8220;fadeIn&#8220; full_width=&#8220;stretch_row&#8220; content_placement=&#8220;middle&#8220; parallax=&#8220;content-moving&#8220; parallax_image=&#8220;277&#8243; el_class=&#8220;riga_banner ptd30 pbd30 ptm40 pbm40&#8243;][vc_column width=&#8220;1\/2&#8243;]<style>.vcex-image.vcex_6a57e67766a74 .vcex-image-inner{max-width:600px;}<\/style><figure class=\"vcex-image vcex-module vcex_6a57e67766a74\"><div class=\"vcex-image-inner wpex-relative wpex-inline-block\"><img width=\"1000\" height=\"239\" src=\"https:\/\/volumec.com\/wp-content\/uploads\/2024\/12\/logo-Volumec.png\" class=\"vcex-image-img wpex-align-middle\" alt=\"\" loading=\"lazy\" decoding=\"async\" srcset=\"https:\/\/volumec.com\/wp-content\/uploads\/2024\/12\/logo-Volumec.png 1000w, https:\/\/volumec.com\/wp-content\/uploads\/2024\/12\/logo-Volumec-300x72.png 300w, https:\/\/volumec.com\/wp-content\/uploads\/2024\/12\/logo-Volumec-768x184.png 768w, https:\/\/volumec.com\/wp-content\/uploads\/2024\/12\/logo-Volumec-600x143.png 600w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/div><\/figure>[\/vc_column][vc_column width=&#8220;1\/2&#8243; el_class=&#8220;ptm40 cm&#8220;][vc_column_text css=&#8220;&#8220; color=&#8220;#ffffff&#8220; font_size=&#8220;d:100px|pl:45px|pp:45px&#8220; line_height=&#8220;110%&#8220; font_weight=&#8220;300&#8243;]Be <strong>innovative<\/strong>[\/vc_column_text][\/vc_column][\/vc_row]\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row full_width=&#8220;stretch_row&#8220; css=&#8220;.vc_custom_1741128562174{padding-top: 70px !important;padding-bottom: 70px !important;background: #13212E url(http:\/\/volumec.com\/wp-content\/uploads\/2024\/12\/Be-innovative.jpg?id=277) !important;}&#8220;][vc_column][vc_column_text css=&#8220;&#8220; text_align=&#8220;center&#8220; color=&#8220;#ffffff&#8220;] EAT 3 [\/vc_column_text][\/vc_column][\/vc_row][vc_row full_width=&#8220;stretch_row&#8220; el_class=&#8220;ptd80 pbd80 ptm40 pbm40&#8243;][vc_column width=&#8220;1\/2&#8243;][vc_column_text css=&#8220;&#8220; text_transform=&#8220;uppercase&#8220;] Ausbalancierter Gelenkarm [\/vc_column_text][vc_column_text css=&#8220;&#8220; el_class=&#8220;mtd50 mtm40 mbd40 mbm30&#8243;]Der dreifach schwenkbare Arm EAT3 erm\u00f6glicht es Ihnen, schwere Werkzeuge auszubalancieren und hohe Arbeitsdrehmomente zu bew\u00e4ltigen.[\/vc_column_text][vc_row_inner][vc_column_inner width=&#8220;1\/3&#8243;][vc_column_text css=&#8220;&#8220; text_align=&#8220;center&#8220; el_class=&#8220;testata_fake_tabella&#8220; color=&#8220;#ffffff&#8220; font_size=&#8220;18px&#8220; font_family=&#8220;Manrope&#8220; line_height=&#8220;22px&#8220;&hellip;<\/p>\n","protected":false},"author":3,"featured_media":0,"parent":464,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"class_list":["post-3875","page","type-page","status-publish","hentry","entry","no-media"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>EAT 3 - Volumec<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/volumec.com\/de\/ausbalanciertes-gelenkarm-system\/eat-3\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"EAT 3 - Volumec\" \/>\n<meta property=\"og:description\" content=\"[vc_row full_width=&#8220;stretch_row&#8220; css=&#8220;.vc_custom_1741128562174{padding-top: 70px !important;padding-bottom: 70px !important;background: #13212E url(http:\/\/volumec.com\/wp-content\/uploads\/2024\/12\/Be-innovative.jpg?id=277) !important;}&#8220;][vc_column][vc_column_text css=&#8220;&#8220; text_align=&#8220;center&#8220; color=&#8220;#ffffff&#8220;] EAT 3 [\/vc_column_text][\/vc_column][\/vc_row][vc_row full_width=&#8220;stretch_row&#8220; el_class=&#8220;ptd80 pbd80 ptm40 pbm40&#8243;][vc_column width=&#8220;1\/2&#8243;][vc_column_text css=&#8220;&#8220; text_transform=&#8220;uppercase&#8220;] Ausbalancierter Gelenkarm [\/vc_column_text][vc_column_text css=&#8220;&#8220; el_class=&#8220;mtd50 mtm40 mbd40 mbm30&#8243;]Der dreifach schwenkbare Arm EAT3 erm\u00f6glicht es Ihnen, schwere Werkzeuge auszubalancieren und hohe Arbeitsdrehmomente zu bew\u00e4ltigen.[\/vc_column_text][vc_row_inner][vc_column_inner width=&#8220;1\/3&#8243;][vc_column_text css=&#8220;&#8220; text_align=&#8220;center&#8220; el_class=&#8220;testata_fake_tabella&#8220; color=&#8220;#ffffff&#8220; font_size=&#8220;18px&#8220; font_family=&#8220;Manrope&#8220; line_height=&#8220;22px&#8220;&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/volumec.com\/de\/ausbalanciertes-gelenkarm-system\/eat-3\/\" \/>\n<meta property=\"og:site_name\" content=\"Volumec\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-27T12:03:27+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"9\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/volumec.com\/de\/ausbalanciertes-gelenkarm-system\/eat-3\/\",\"url\":\"https:\/\/volumec.com\/de\/ausbalanciertes-gelenkarm-system\/eat-3\/\",\"name\":\"EAT 3 - Volumec\",\"isPartOf\":{\"@id\":\"https:\/\/www.volumec.com\/en\/#website\"},\"datePublished\":\"2025-02-19T16:30:11+00:00\",\"dateModified\":\"2025-10-27T12:03:27+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/volumec.com\/de\/ausbalanciertes-gelenkarm-system\/eat-3\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/volumec.com\/de\/ausbalanciertes-gelenkarm-system\/eat-3\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/volumec.com\/de\/ausbalanciertes-gelenkarm-system\/eat-3\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/volumec.com\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ausbalanciertes Gelenkarm System\",\"item\":\"https:\/\/volumec.com\/de\/ausbalanciertes-gelenkarm-system\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"EAT 3\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.volumec.com\/en\/#website\",\"url\":\"https:\/\/www.volumec.com\/en\/\",\"name\":\"Volumec.com\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.volumec.com\/en\/#organization\"},\"alternateName\":\"be innovative\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.volumec.com\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.volumec.com\/en\/#organization\",\"name\":\"Volumec\",\"url\":\"https:\/\/www.volumec.com\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.volumec.com\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/volumec.com\/wp-content\/uploads\/2024\/12\/Volumec-logo.png\",\"contentUrl\":\"https:\/\/volumec.com\/wp-content\/uploads\/2024\/12\/Volumec-logo.png\",\"width\":320,\"height\":77,\"caption\":\"Volumec\"},\"image\":{\"@id\":\"https:\/\/www.volumec.com\/en\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"EAT 3 - Volumec","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/volumec.com\/de\/ausbalanciertes-gelenkarm-system\/eat-3\/","og_locale":"de_DE","og_type":"article","og_title":"EAT 3 - Volumec","og_description":"[vc_row full_width=&#8220;stretch_row&#8220; css=&#8220;.vc_custom_1741128562174{padding-top: 70px !important;padding-bottom: 70px !important;background: #13212E url(http:\/\/volumec.com\/wp-content\/uploads\/2024\/12\/Be-innovative.jpg?id=277) !important;}&#8220;][vc_column][vc_column_text css=&#8220;&#8220; text_align=&#8220;center&#8220; color=&#8220;#ffffff&#8220;] EAT 3 [\/vc_column_text][\/vc_column][\/vc_row][vc_row full_width=&#8220;stretch_row&#8220; el_class=&#8220;ptd80 pbd80 ptm40 pbm40&#8243;][vc_column width=&#8220;1\/2&#8243;][vc_column_text css=&#8220;&#8220; text_transform=&#8220;uppercase&#8220;] Ausbalancierter Gelenkarm [\/vc_column_text][vc_column_text css=&#8220;&#8220; el_class=&#8220;mtd50 mtm40 mbd40 mbm30&#8243;]Der dreifach schwenkbare Arm EAT3 erm\u00f6glicht es Ihnen, schwere Werkzeuge auszubalancieren und hohe Arbeitsdrehmomente zu bew\u00e4ltigen.[\/vc_column_text][vc_row_inner][vc_column_inner width=&#8220;1\/3&#8243;][vc_column_text css=&#8220;&#8220; text_align=&#8220;center&#8220; el_class=&#8220;testata_fake_tabella&#8220; color=&#8220;#ffffff&#8220; font_size=&#8220;18px&#8220; font_family=&#8220;Manrope&#8220; line_height=&#8220;22px&#8220;&hellip;","og_url":"https:\/\/volumec.com\/de\/ausbalanciertes-gelenkarm-system\/eat-3\/","og_site_name":"Volumec","article_modified_time":"2025-10-27T12:03:27+00:00","twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"9\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/volumec.com\/de\/ausbalanciertes-gelenkarm-system\/eat-3\/","url":"https:\/\/volumec.com\/de\/ausbalanciertes-gelenkarm-system\/eat-3\/","name":"EAT 3 - Volumec","isPartOf":{"@id":"https:\/\/www.volumec.com\/en\/#website"},"datePublished":"2025-02-19T16:30:11+00:00","dateModified":"2025-10-27T12:03:27+00:00","breadcrumb":{"@id":"https:\/\/volumec.com\/de\/ausbalanciertes-gelenkarm-system\/eat-3\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/volumec.com\/de\/ausbalanciertes-gelenkarm-system\/eat-3\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/volumec.com\/de\/ausbalanciertes-gelenkarm-system\/eat-3\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/volumec.com\/de\/"},{"@type":"ListItem","position":2,"name":"Ausbalanciertes Gelenkarm System","item":"https:\/\/volumec.com\/de\/ausbalanciertes-gelenkarm-system\/"},{"@type":"ListItem","position":3,"name":"EAT 3"}]},{"@type":"WebSite","@id":"https:\/\/www.volumec.com\/en\/#website","url":"https:\/\/www.volumec.com\/en\/","name":"Volumec.com","description":"","publisher":{"@id":"https:\/\/www.volumec.com\/en\/#organization"},"alternateName":"be innovative","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.volumec.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.volumec.com\/en\/#organization","name":"Volumec","url":"https:\/\/www.volumec.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.volumec.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/volumec.com\/wp-content\/uploads\/2024\/12\/Volumec-logo.png","contentUrl":"https:\/\/volumec.com\/wp-content\/uploads\/2024\/12\/Volumec-logo.png","width":320,"height":77,"caption":"Volumec"},"image":{"@id":"https:\/\/www.volumec.com\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/volumec.com\/de\/wp-json\/wp\/v2\/pages\/3875","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/volumec.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/volumec.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/volumec.com\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/volumec.com\/de\/wp-json\/wp\/v2\/comments?post=3875"}],"version-history":[{"count":14,"href":"https:\/\/volumec.com\/de\/wp-json\/wp\/v2\/pages\/3875\/revisions"}],"predecessor-version":[{"id":9568,"href":"https:\/\/volumec.com\/de\/wp-json\/wp\/v2\/pages\/3875\/revisions\/9568"}],"up":[{"embeddable":true,"href":"https:\/\/volumec.com\/de\/wp-json\/wp\/v2\/pages\/464"}],"wp:attachment":[{"href":"https:\/\/volumec.com\/de\/wp-json\/wp\/v2\/media?parent=3875"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}