{"id":3864,"date":"2025-02-19T16:46:37","date_gmt":"2025-02-19T15:46:37","guid":{"rendered":"http:\/\/volumec.com\/ausbalanciertes-gelenkarm-system\/easyarm-4\/"},"modified":"2025-10-27T12:57:34","modified_gmt":"2025-10-27T11:57:34","slug":"easyarm-4","status":"publish","type":"page","link":"https:\/\/volumec.com\/de\/ausbalanciertes-gelenkarm-system\/easyarm-4\/","title":{"rendered":"EASYARM 4"},"content":{"rendered":"<div class=\"wpb-content-wrapper\">[vc_row full_width=&#8220;stretch_row&#8220; css=&#8220;.vc_custom_1741128533329{padding-top: 70px !important;padding-bottom: 70px !important;background: #13212E url(http:\/\/volumec.com\/wp-content\/uploads\/2024\/12\/Be-innovative.jpg?id=277) !important;}&#8220;][vc_column][vc_column_text css=&#8220;&#8220; text_align=&#8220;center&#8220; color=&#8220;#ffffff&#8220;]\n<h1>EASYARM 4<\/h1>\n[\/vc_column_text]<style>.vcex-breadcrumbs.vcex_6a57e67ca7ea4 .sep{color:#ffffff;}.vcex-breadcrumbs.vcex_6a57e67ca7ea4{text-align:center;color:#ffffff;--wpex-link-color:#ffffff;}<\/style><nav class=\"vcex-breadcrumbs vcex-breadcrumbs--links-inherit-color vcex-breadcrumbs--custom-color vcex_6a57e67ca7ea4\"><span><span><a href=\"https:\/\/volumec.com\/de\/\">Home<\/a><\/span><\/span><\/nav>[\/vc_column][\/vc_row][vc_row full_width=&#8220;stretch_row&#8220; el_class=&#8220;ptd80 pbd80 ptm40 pbm40&#8243;][vc_column width=&#8220;1\/2&#8243;][vc_column_text css=&#8220;&#8220; text_transform=&#8220;uppercase&#8220;]\n<h2><strong>Ausbalanciertes Gelenkarm-System<br \/>\n<\/strong><\/h2>\n[\/vc_column_text][vc_column_text css=&#8220;&#8220; el_class=&#8220;mtd50 mtm40 mbd40 mbm30&#8243;]Die Baureihe EasyArm wurde konzipiert um Werkzeuge oder sonstige Apparate, bis zu einem max. Gewicht von 30 kg, aufzunehmen.<br \/>\nDer Aufbau dieses Systems, komplett aus Luftfahrt-Aluminium hergestellt, garantiert flie\u00dfende kontrollierte Bewegungen, sowie korrekte Positionierung des Werkzeuges.<br \/>\nVibrationen und Drehmomente werden absorbiert.<br \/>\nDurch die Auswahl an verschiedenen Anschlag- und Klemmpositionen sowie diversem Zubeh\u00f6r, ergeben sich viele verschiedene M\u00f6glichkeiten der Bearbeitung bzw. Anwendung. Dadurch k\u00f6nnen unterschiedliche Arbeitsbereiche realisiert werden.<br \/>\nDie Ben\u00fctzung dieser ausbalancierten Gelenkarme verhindert die vorzeitige Ersch\u00f6pfung der Mitarbeiter. Eine h\u00f6here Produktivit\u00e4t und ein gesundheitlich besseres Arbeiten sind hier klar als Vorteile zu nennen.<br \/>\nEasyArm ist eine komplette Baureihe von ausbalancierten Gelenkarmen, die unterschiedlichste Anwendungen erm\u00f6glicht.[\/vc_column_text]<div class=\"cq-datatable   cq-datatable-medium cq-datatable-gray\"><div class=\"cq-datatable-row cq-datatable-header cq-datatable-bg-customized\" style=\"background:#121A1E\"><div class=\"cq-datatable-cell\" data-title=\"Arbeitsradius\"> Arbeitsradius <\/div><div class=\"cq-datatable-cell\" data-title=\"Vertikales Laufen\"> Vertikales Laufen <\/div><div class=\"cq-datatable-cell\" data-title=\"Drehung\"> Drehung <\/div><div class=\"cq-datatable-cell\" data-title=\"Gewicht Arm\"> Gewicht Arm <\/div><\/div><div class=\"cq-datatable-row cq-datatable-data\"><div class=\"cq-datatable-cell\"> 1800 mm + Kopf <\/div><div class=\"cq-datatable-cell\"> 1450 mm <\/div><div class=\"cq-datatable-cell\"> 360 \u00b0 <\/div><div class=\"cq-datatable-cell\"> 20-22 kg <\/div><\/div><div class=\"cq-datatable-row cq-datatable-data\"><div class=\"cq-datatable-cell\"> 72 in + Kopf <\/div><div class=\"cq-datatable-cell\"> 57 in <\/div><div class=\"cq-datatable-cell\"> 360 \u00b0 <\/div><div class=\"cq-datatable-cell\"> 42-18 lbs <\/div><\/div>\n<\/div>[vc_row_inner][vc_column_inner width=&#8220;1\/3&#8243;][vc_column_text css=&#8220;&#8220; text_align=&#8220;center&#8220; el_class=&#8220;testata_fake_tabella&#8220; color=&#8220;#ffffff&#8220; font_size=&#8220;18px&#8220; font_family=&#8220;Manrope&#8220; line_height=&#8220;22px&#8220; font_weight=&#8220;400&#8243;]Kompatible Kopfzeilen[\/vc_column_text][vc_column_text css=&#8220;.vc_custom_1743504157560{margin-top: 10px !important;}&#8220; text_align=&#8220;center&#8220;]Alle[\/vc_column_text][\/vc_column_inner][vc_column_inner el_class=&#8220;mtm20&#8243; width=&#8220;1\/3&#8243;][vc_column_text css=&#8220;&#8220; text_align=&#8220;center&#8220; el_class=&#8220;testata_fake_tabella&#8220; color=&#8220;#ffffff&#8220; font_size=&#8220;18px&#8220; font_family=&#8220;Manrope&#8220; line_height=&#8220;22px&#8220; font_weight=&#8220;400&#8243;]BANKBEFESTIGUNG (standard)[\/vc_column_text]<figure class=\"vcex-image vcex-module wpex-text-center\"><div class=\"vcex-image-inner wpex-relative wpex-inline-block vc_custom_1739981617333\"><img width=\"200\" height=\"200\" src=\"https:\/\/volumec.com\/wp-content\/uploads\/2025\/02\/fb-ea1.png\" class=\"vcex-image-img wpex-align-middle\" alt=\"\" loading=\"lazy\" decoding=\"async\" srcset=\"https:\/\/volumec.com\/wp-content\/uploads\/2025\/02\/fb-ea1.png 200w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/02\/fb-ea1-150x150.png 150w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/02\/fb-ea1-100x100.png 100w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" \/><\/div><\/figure>[\/vc_column_inner][vc_column_inner el_class=&#8220;mtm20&#8243; width=&#8220;1\/3&#8243;][vc_column_text css=&#8220;&#8220; text_align=&#8220;center&#8220; el_class=&#8220;testata_fake_tabella&#8220; color=&#8220;#ffffff&#8220; font_size=&#8220;18px&#8220; font_family=&#8220;Manrope&#8220; line_height=&#8220;22px&#8220; font_weight=&#8220;400&#8243;]DECKENMONTAGE Version (S)[\/vc_column_text]<figure class=\"vcex-image vcex-module wpex-text-center\"><div class=\"vcex-image-inner wpex-relative wpex-inline-block vc_custom_1739981631587\"><img width=\"200\" height=\"150\" src=\"https:\/\/volumec.com\/wp-content\/uploads\/2025\/02\/fs-ea1.png\" class=\"vcex-image-img wpex-align-middle\" alt=\"\" loading=\"lazy\" decoding=\"async\" \/><\/div><\/figure>[\/vc_column_inner][\/vc_row_inner][\/vc_column][vc_column width=&#8220;1\/2&#8243; el_class=&#8220;mtm20&#8243;]<div class=\"wpex-slider-preloaderimg wpex-relative\"><img width=\"800\" height=\"800\" src=\"https:\/\/volumec.com\/wp-content\/uploads\/2025\/10\/Ausbalanciertes-Gelenkarm-System-EASYARM-4-01.png\" class=\"skip-lazy\" alt=\"\" data-no-lazy=\"1\" srcset=\"https:\/\/volumec.com\/wp-content\/uploads\/2025\/10\/Ausbalanciertes-Gelenkarm-System-EASYARM-4-01.png 800w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/10\/Ausbalanciertes-Gelenkarm-System-EASYARM-4-01-300x300.png 300w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/10\/Ausbalanciertes-Gelenkarm-System-EASYARM-4-01-150x150.png 150w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/10\/Ausbalanciertes-Gelenkarm-System-EASYARM-4-01-768x768.png 768w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/10\/Ausbalanciertes-Gelenkarm-System-EASYARM-4-01-600x600.png 600w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/10\/Ausbalanciertes-Gelenkarm-System-EASYARM-4-01-100x100.png 100w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/10\/Ausbalanciertes-Gelenkarm-System-EASYARM-4-01-460x460.png 460w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/div><div class=\"vcex-image-slider vcex-module wpex-slider slider-pro wpex-clr\" data-loop=\"true\" data-auto-play-delay=\"5000\" data-animation-speed=\"600\" data-height-animation-duration=\"500\" data-thumbnail-height=\"70\" data-thumbnail-width=\"70\" data-reach-video-action=\"none\"><div class=\"wpex-slider-slides sp-slides\"><div class=\"wpex-slider-slide sp-slide\"><div class=\"wpex-slider-media wpex-relative\"><img width=\"800\" height=\"800\" src=\"https:\/\/volumec.com\/wp-content\/uploads\/2025\/10\/Ausbalanciertes-Gelenkarm-System-EASYARM-4-01.png\" class=\"skip-lazy\" alt=\"\" data-no-lazy=\"1\" srcset=\"https:\/\/volumec.com\/wp-content\/uploads\/2025\/10\/Ausbalanciertes-Gelenkarm-System-EASYARM-4-01.png 800w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/10\/Ausbalanciertes-Gelenkarm-System-EASYARM-4-01-300x300.png 300w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/10\/Ausbalanciertes-Gelenkarm-System-EASYARM-4-01-150x150.png 150w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/10\/Ausbalanciertes-Gelenkarm-System-EASYARM-4-01-768x768.png 768w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/10\/Ausbalanciertes-Gelenkarm-System-EASYARM-4-01-600x600.png 600w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/10\/Ausbalanciertes-Gelenkarm-System-EASYARM-4-01-100x100.png 100w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/10\/Ausbalanciertes-Gelenkarm-System-EASYARM-4-01-460x460.png 460w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/div><\/div><div class=\"wpex-slider-slide sp-slide\"><div class=\"wpex-slider-media wpex-relative\"><img width=\"800\" height=\"800\" src=\"https:\/\/volumec.com\/wp-content\/uploads\/2025\/10\/Ausbalanciertes-Gelenkarm-System-EASYARM-4-02.png\" class=\"skip-lazy\" alt=\"\" data-no-lazy=\"1\" srcset=\"https:\/\/volumec.com\/wp-content\/uploads\/2025\/10\/Ausbalanciertes-Gelenkarm-System-EASYARM-4-02.png 800w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/10\/Ausbalanciertes-Gelenkarm-System-EASYARM-4-02-300x300.png 300w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/10\/Ausbalanciertes-Gelenkarm-System-EASYARM-4-02-150x150.png 150w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/10\/Ausbalanciertes-Gelenkarm-System-EASYARM-4-02-768x768.png 768w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/10\/Ausbalanciertes-Gelenkarm-System-EASYARM-4-02-600x600.png 600w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/10\/Ausbalanciertes-Gelenkarm-System-EASYARM-4-02-100x100.png 100w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/10\/Ausbalanciertes-Gelenkarm-System-EASYARM-4-02-460x460.png 460w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/div><\/div><div class=\"wpex-slider-slide sp-slide\"><div class=\"wpex-slider-media wpex-relative\"><img width=\"800\" height=\"800\" src=\"https:\/\/volumec.com\/wp-content\/uploads\/2025\/10\/Ausbalanciertes-Gelenkarm-System-EASYARM-4-03.png\" class=\"skip-lazy\" alt=\"\" data-no-lazy=\"1\" srcset=\"https:\/\/volumec.com\/wp-content\/uploads\/2025\/10\/Ausbalanciertes-Gelenkarm-System-EASYARM-4-03.png 800w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/10\/Ausbalanciertes-Gelenkarm-System-EASYARM-4-03-300x300.png 300w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/10\/Ausbalanciertes-Gelenkarm-System-EASYARM-4-03-150x150.png 150w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/10\/Ausbalanciertes-Gelenkarm-System-EASYARM-4-03-768x768.png 768w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/10\/Ausbalanciertes-Gelenkarm-System-EASYARM-4-03-600x600.png 600w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/10\/Ausbalanciertes-Gelenkarm-System-EASYARM-4-03-100x100.png 100w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/10\/Ausbalanciertes-Gelenkarm-System-EASYARM-4-03-460x460.png 460w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/div><\/div><div class=\"wpex-slider-slide sp-slide\"><div class=\"wpex-slider-media wpex-relative\"><img width=\"800\" height=\"800\" src=\"https:\/\/volumec.com\/wp-content\/uploads\/2025\/10\/Ausbalanciertes-Gelenkarm-System-EASYARM-4-04.png\" class=\"skip-lazy\" alt=\"\" data-no-lazy=\"1\" srcset=\"https:\/\/volumec.com\/wp-content\/uploads\/2025\/10\/Ausbalanciertes-Gelenkarm-System-EASYARM-4-04.png 800w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/10\/Ausbalanciertes-Gelenkarm-System-EASYARM-4-04-300x300.png 300w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/10\/Ausbalanciertes-Gelenkarm-System-EASYARM-4-04-150x150.png 150w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/10\/Ausbalanciertes-Gelenkarm-System-EASYARM-4-04-768x768.png 768w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/10\/Ausbalanciertes-Gelenkarm-System-EASYARM-4-04-600x600.png 600w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/10\/Ausbalanciertes-Gelenkarm-System-EASYARM-4-04-100x100.png 100w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/10\/Ausbalanciertes-Gelenkarm-System-EASYARM-4-04-460x460.png 460w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/div><\/div><\/div><\/div>[\/vc_column][\/vc_row][vc_row full_width=&#8220;stretch_row&#8220; content_placement=&#8220;middle&#8220; el_class=&#8220;ptd70 pbd50 ptm50 pbm50&#8243; css=&#8220;.vc_custom_1734433172112{background-color: #131A1F !important;}&#8220;][vc_column css_animation=&#8220;fadeInLeft&#8220;][vc_column_text css=&#8220;&#8220; color=&#8220;#0c8df2&#8243; font_size=&#8220;19px&#8220; text_align=&#8220;center&#8220; font_weight=&#8220;700&#8243;]Die Einf\u00fchrung der EASYARM-Arme erm\u00f6glicht es schlie\u00dflich, die Anforderungen der TU 81\/2008 (insbesondere der Artikel 168 und 203) zu erf\u00fcllen.[\/vc_column_text][vc_column_text css=&#8220;&#8220; el_class=&#8220;mtd30 mtm30&#8243; text_align=&#8220;center&#8220; color=&#8220;#ffffff&#8220;]\n<p class=\"\" data-start=\"42\" data-end=\"764\">Art. 168 Der Arbeitgeber trifft die erforderlichen organisatorischen Ma\u00dfnahmen und setzt geeignete Mittel, insbesondere mechanische Ausstattungen, ein, um die Notwendigkeit der manuellen Handhabung von Lasten durch die Arbeitnehmer zu vermeiden. Wenn die manuelle Handhabung von Lasten durch die Arbeitnehmer nicht vermieden werden kann, trifft der Arbeitgeber die erforderlichen organisatorischen Ma\u00dfnahmen, setzt geeignete Mittel ein und stellt den Arbeitnehmern die geeigneten Hilfsmittel zur Verf\u00fcgung, um das Risiko der manuellen Handhabung dieser Lasten zu verringern [\u2026]\n<p class=\"\" data-start=\"766\" data-end=\"1336\">Art. 203 [\u2026] Der Arbeitgeber erstellt und wendet ein Programm technischer oder organisatorischer Ma\u00dfnahmen an, das darauf abzielt, die Exposition und die Risiken auf ein Minimum zu reduzieren [\u2026], wobei insbesondere Folgendes ber\u00fccksichtigt wird: a) andere Arbeitsmethoden, die eine geringere Exposition gegen\u00fcber mechanischen Vibrationen erfordern; b) die Auswahl geeigneter Arbeitsmittel, die unter Ber\u00fccksichtigung der ergonomischen Prinzipien entworfen wurden und unter Ber\u00fccksichtigung der auszuf\u00fchrenden Arbeit das geringstm\u00f6gliche Ma\u00df an Vibrationen erzeugen [\u2026]\n[\/vc_column_text][\/vc_column][\/vc_row][vc_row el_class=&#8220;mtd20 mtm20&#8243; css=&#8220;.vc_custom_1741446878883{margin-top: 50px !important;margin-bottom: 50px !important;}&#8220;][vc_column width=&#8220;1\/4&#8243; el_class=&#8220;cd cm&#8220;][\/vc_column][vc_column width=&#8220;1\/4&#8243; el_class=&#8220;popmake-7008&#8243;]<style>.vcex-button.vcex_6a57e67cb7679{border-radius:0px;color:#000000!important;padding:20px;border:2px solid #FE0100;font-family:Manrope;font-size:16px;font-weight:700;}.vcex-button.vcex_6a57e67cb7679:hover{color:#000000!important;}<\/style><a href=\"#\" class=\"vcex-button theme-button outline inline bottone1 bottone_rosso vcex_6a57e67cb7679\"><span class=\"vcex-button-inner theme-button-inner wpex-flex wpex-flex-wrap wpex-items-center wpex-justify-center\">ENTLADEN DIE BROSCH\u00dcRE<span class=\"vcex-button-icon vcex-icon-wrap theme-button-icon-right\"><span aria-hidden=\"true\" class=\"fas fa-arrow-right\"><\/span><\/span><\/span><\/a> [\/vc_column][vc_column width=&#8220;1\/4&#8243;]<style>.vcex-button.vcex_6a57e67cba38d{border-radius:0px;color:#000000!important;padding:20px;border:2px solid #0b8df1;font-family:Manrope;font-size:16px;font-weight:700;}.vcex-button.vcex_6a57e67cba38d:hover{color:#000000!important;}<\/style><div class=\"theme-button-wrap textcenter wpex-clr\"><a href=\"http:\/\/volumec.com\/de\/fragen-sie-uns-an\/\" class=\"vcex-button theme-button outline align-center inline bottone1 mtd30 mtm30 vcex_6a57e67cba38d\"><span class=\"vcex-button-inner theme-button-inner wpex-flex wpex-flex-wrap wpex-items-center wpex-justify-center\">FRAGEN SIE UNS AN<span class=\"vcex-button-icon vcex-icon-wrap theme-button-icon-right\"><span aria-hidden=\"true\" class=\"fas fa-arrow-right\"><\/span><\/span><\/span><\/a><\/div> [\/vc_column][vc_column width=&#8220;1\/4&#8243;][\/vc_column][\/vc_row][vc_row full_width=&#8220;stretch_row&#8220; local_scroll_id=&#8220;info&#8220; css=&#8220;.vc_custom_1737457059910{background-color: #F1F1F1 !important;}&#8220; el_class=&#8220;ptd50 ptm50 pbd50 pbm50 mtd20 mtm20&#8243;][vc_column width=&#8220;1\/2&#8243;][vc_column_text css=&#8220;&#8220;]\n<h2 style=\"text-align: center;\"><strong>Vorteile<\/strong><\/h2>\n[\/vc_column_text]<style>.vcex-icon-box.vcex_6a57e67cbf9fe .vcex-icon-box-heading{margin-bottom:0px;font-weight:700;}<\/style><div class=\"vcex-module vcex-icon-box vcex-icon-box-one wpex-flex wpex-items-center wpex-text-left mtd30 mbd30 mtm20 mbm20 vcex_6a57e67cbf9fe\"><div class=\"vcex-icon-box-symbol vcex-icon-box-symbol--icon wpex-flex-shrink-0 wpex-mr-25\"><div class=\"vcex-icon-box-icon wpex-items-center wpex-justify-center wpex-child-inherit-color wpex-text-center wpex-leading-none wpex-flex wpex-text-1\"><span class=\"fa-light fa-arrow-down-right\" aria-hidden=\"true\"><\/span><\/div><\/div><div class=\"vcex-icon-box-text wpex-flex-grow\"><div class=\"vcex-icon-box-content wpex-last-mb-0 wpex-clr\"><p class=\"text-justify\"><i class=\"fas fa-caret-right mr-2\"><\/i>Befreien Sie Ihr Werkzeug vom Gewicht, reduzieren Sie die Erm\u00fcdung des Bedieners, sch\u00fctzen Sie die Gesundheit und steigern Sie die Produktivit\u00e4t.<\/p>\n<\/div><\/div><\/div><style>.vcex-icon-box.vcex_6a57e67cc2898 .vcex-icon-box-heading{margin-bottom:0px;font-weight:700;}<\/style><div class=\"vcex-module vcex-icon-box vcex-icon-box-one wpex-flex wpex-items-center wpex-text-left mtd30 mbd30 mtm20 mbm20 vcex_6a57e67cc2898\"><div class=\"vcex-icon-box-symbol vcex-icon-box-symbol--icon wpex-flex-shrink-0 wpex-mr-25\"><div class=\"vcex-icon-box-icon wpex-items-center wpex-justify-center wpex-child-inherit-color wpex-text-center wpex-leading-none wpex-flex wpex-text-1\"><span class=\"fa-light fa-arrow-down-right\" aria-hidden=\"true\"><\/span><\/div><\/div><div class=\"vcex-icon-box-text wpex-flex-grow\"><div class=\"vcex-icon-box-content wpex-last-mb-0 wpex-clr\"><p class=\"text-justify\"><i class=\"fas fa-caret-right mr-2\"><\/i>Erm\u00f6glicht eine reibungslose und einfache Bewegung in jede Richtung.<\/p>\n<\/div><\/div><\/div><style>.vcex-icon-box.vcex_6a57e67cc558d .vcex-icon-box-heading{margin-bottom:0px;font-weight:700;}<\/style><div class=\"vcex-module vcex-icon-box vcex-icon-box-one wpex-flex wpex-items-center wpex-text-left mtd30 mbd30 mtm20 mbm20 vcex_6a57e67cc558d\"><div class=\"vcex-icon-box-symbol vcex-icon-box-symbol--icon wpex-flex-shrink-0 wpex-mr-25\"><div class=\"vcex-icon-box-icon wpex-items-center wpex-justify-center wpex-child-inherit-color wpex-text-center wpex-leading-none wpex-flex wpex-text-1\"><span class=\"fa-light fa-arrow-down-right\" aria-hidden=\"true\"><\/span><\/div><\/div><div class=\"vcex-icon-box-text wpex-flex-grow\"><div class=\"vcex-icon-box-content wpex-last-mb-0 wpex-clr\"><p class=\"text-justify\"><i class=\"fas fa-caret-right mr-2\"><\/i>Nimmt das durch den Werkzeuggebrauch entstehende Drehmoment und die Torsion auf.<\/p>\n<\/div><\/div><\/div><style>.vcex-icon-box.vcex_6a57e67cc81e7 .vcex-icon-box-heading{margin-bottom:0px;font-weight:700;}<\/style><div class=\"vcex-module vcex-icon-box vcex-icon-box-one wpex-flex wpex-items-center wpex-text-left mtd30 mbd30 mtm20 mbm20 vcex_6a57e67cc81e7\"><div class=\"vcex-icon-box-symbol vcex-icon-box-symbol--icon wpex-flex-shrink-0 wpex-mr-25\"><div class=\"vcex-icon-box-icon wpex-items-center wpex-justify-center wpex-child-inherit-color wpex-text-center wpex-leading-none wpex-flex wpex-text-1\"><span class=\"fa-light fa-arrow-down-right\" aria-hidden=\"true\"><\/span><\/div><\/div><div class=\"vcex-icon-box-text wpex-flex-grow\"><div class=\"vcex-icon-box-content wpex-last-mb-0 wpex-clr\"><p class=\"text-justify\"><i class=\"fas fa-caret-right mr-2\"><\/i>Komplett bei unserem Unternehmen in Italien hergestellt.<\/p>\n<\/div><\/div><\/div><style>.vcex-icon-box.vcex_6a57e67ccaea0 .vcex-icon-box-heading{margin-bottom:0px;font-weight:700;}<\/style><div class=\"vcex-module vcex-icon-box vcex-icon-box-one wpex-flex wpex-items-center wpex-text-left mtd30 mbd30 mtm20 mbm20 vcex_6a57e67ccaea0\"><div class=\"vcex-icon-box-symbol vcex-icon-box-symbol--icon wpex-flex-shrink-0 wpex-mr-25\"><div class=\"vcex-icon-box-icon wpex-items-center wpex-justify-center wpex-child-inherit-color wpex-text-center wpex-leading-none wpex-flex wpex-text-1\"><span class=\"fa-light fa-arrow-down-right\" aria-hidden=\"true\"><\/span><\/div><\/div><div class=\"vcex-icon-box-text wpex-flex-grow\"><div class=\"vcex-icon-box-content wpex-last-mb-0 wpex-clr\"><p class=\"text-justify\"><i class=\"fas fa-caret-right mr-2\"><\/i>Bietet eine vollst\u00e4ndige Palette von L\u00f6sungen, die f\u00fcr jede Aufgabe geeignet sind.<\/p>\n<\/div><\/div><\/div>[\/vc_column][vc_column width=&#8220;1\/2&#8243; el_class=&#8220;mtm40&#8243;][vc_column_text css=&#8220;&#8220;]\n<h2 style=\"text-align: center;\"><strong>Arbeitsbereich<\/strong><\/h2>\n[\/vc_column_text]<figure class=\"vcex-image vcex-module wpex-text-center mtd30 mtm20\"><div class=\"vcex-image-inner wpex-relative wpex-inline-block\"><a href=\"https:\/\/volumec.com\/wp-content\/uploads\/2025\/03\/area-di-lavoro-easyarm-4.jpg\" class=\"wpex-lightbox\"><img width=\"800\" height=\"553\" src=\"https:\/\/volumec.com\/wp-content\/uploads\/2025\/03\/area-di-lavoro-easyarm-4.jpg\" class=\"vcex-image-img wpex-align-middle\" alt=\"\" loading=\"lazy\" decoding=\"async\" srcset=\"https:\/\/volumec.com\/wp-content\/uploads\/2025\/03\/area-di-lavoro-easyarm-4.jpg 800w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/03\/area-di-lavoro-easyarm-4-300x207.jpg 300w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/03\/area-di-lavoro-easyarm-4-768x531.jpg 768w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/03\/area-di-lavoro-easyarm-4-600x415.jpg 600w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/div><\/figure>[\/vc_column][\/vc_row][vc_row el_class=&#8220;mtd70 mtm50&#8243;][vc_column][vc_column_text css=&#8220;&#8220;]\n<h2><strong>EA4<\/strong> &#8211; Multi Gelenkarm<\/h2>\n[\/vc_column_text][vc_column_text css=&#8220;&#8220; el_class=&#8220;mtd20 mtm20 mbd20 mbm20&#8243;]Die spezielle Konstruktion erm\u00f6glicht eine maximale Flexibilit\u00e4t und Bewegungsfreiheit. Durch das Doppelgelenk l\u00e4sst sich ein gro\u00dfer Arbeitsbereich auch in der H\u00f6he realisieren. Ferner besteht auch die M\u00f6glichkeit in der N\u00e4he der Befestigungsbasis zu arbeiten.ZERO GRAVITY.[\/vc_column_text][\/vc_column][\/vc_row][vc_row el_class=&#8220;mtd40 mtm30&#8243;][vc_column width=&#8220;1\/2&#8243;]<div class=\"cq-datatable   cq-datatable-medium cq-datatable-gray\"><div class=\"cq-datatable-row cq-datatable-header cq-datatable-bg-customized\" style=\"background:#121A1E\"><div class=\"cq-datatable-cell\" data-title=\"Modell\"> Modell <\/div><div class=\"cq-datatable-cell\" data-title=\"Drehmoment (Nm)\"> Drehmoment (Nm) <\/div><div class=\"cq-datatable-cell\" data-title=\"Gewicht Arm (kg)\"> Gewicht Arm (kg) <\/div><\/div><div class=\"cq-datatable-row cq-datatable-data\"><div class=\"cq-datatable-cell\"> EA186002 <\/div><div class=\"cq-datatable-cell\"> 200 <\/div><div class=\"cq-datatable-cell\"> 1,5 - 2 <\/div><\/div><div class=\"cq-datatable-row cq-datatable-data\"><div class=\"cq-datatable-cell\"> EA186004 <\/div><div class=\"cq-datatable-cell\"> 200 <\/div><div class=\"cq-datatable-cell\"> 2,5 - 5 <\/div><\/div><div class=\"cq-datatable-row cq-datatable-data\"><div class=\"cq-datatable-cell\"> EA186008 <\/div><div class=\"cq-datatable-cell\"> 200 <\/div><div class=\"cq-datatable-cell\"> 5,5 - 8 <\/div><\/div><div class=\"cq-datatable-row cq-datatable-data\"><div class=\"cq-datatable-cell\"> EA186010 <\/div><div class=\"cq-datatable-cell\"> 200 <\/div><div class=\"cq-datatable-cell\"> 8,5 - 10 <\/div><\/div>\n<\/div>[\/vc_column][vc_column width=&#8220;1\/2&#8243;][\/vc_column][\/vc_row][vc_row el_class=&#8220;mtd70 mtm50&#8243;][vc_column][vc_column_text css=&#8220;&#8220;]\n<h2><strong>EAB4<\/strong> &#8211; Multi Gelenkarm mit <strong>Verschlusssystem<\/strong><\/h2>\n[\/vc_column_text][vc_column_text css=&#8220;&#8220; el_class=&#8220;mtd20 mtm20 mbd20 mbm20&#8243;]Die EAB Serie kann als Standartarm benutzt werden, optional kann aber auch die Vertikalachse arretiert werden, dies erm\u00f6glicht ein optimales Arbeiten auf einer H\u00f6he.[\/vc_column_text][\/vc_column][\/vc_row][vc_row el_class=&#8220;mtd40 mtm30&#8243;][vc_column width=&#8220;1\/2&#8243;]<div class=\"cq-datatable   cq-datatable-medium cq-datatable-gray\"><div class=\"cq-datatable-row cq-datatable-header cq-datatable-bg-customized\" style=\"background:#121A1E\"><div class=\"cq-datatable-cell\" data-title=\"Modello\"> Modello <\/div><div class=\"cq-datatable-cell\" data-title=\"Drehmoment (Nm)\"> Drehmoment (Nm) <\/div><div class=\"cq-datatable-cell\" data-title=\"Gewicht Arm (kg)\"> Gewicht Arm (kg) <\/div><\/div><div class=\"cq-datatable-row cq-datatable-data\"><div class=\"cq-datatable-cell\"> EAB186002 <\/div><div class=\"cq-datatable-cell\"> 200 <\/div><div class=\"cq-datatable-cell\"> 1,5 - 2 <\/div><\/div><div class=\"cq-datatable-row cq-datatable-data\"><div class=\"cq-datatable-cell\"> EAB186004 <\/div><div class=\"cq-datatable-cell\"> 200 <\/div><div class=\"cq-datatable-cell\"> 2,5 - 5 <\/div><\/div><div class=\"cq-datatable-row cq-datatable-data\"><div class=\"cq-datatable-cell\"> EAB186008 <\/div><div class=\"cq-datatable-cell\"> 200 <\/div><div class=\"cq-datatable-cell\"> 5,5 - 8 <\/div><\/div><div class=\"cq-datatable-row cq-datatable-data\"><div class=\"cq-datatable-cell\"> EAB186010 <\/div><div class=\"cq-datatable-cell\"> 200 <\/div><div class=\"cq-datatable-cell\"> 8,5 - 10 <\/div><\/div>\n<\/div>[\/vc_column][vc_column width=&#8220;1\/2&#8243;]<figure class=\"vcex-image vcex-module wpex-text-center mtd30 mtm20\"><div class=\"vcex-image-inner wpex-relative wpex-inline-block\"><img width=\"800\" height=\"352\" src=\"https:\/\/volumec.com\/wp-content\/uploads\/2025\/01\/braccio-articolato-bloccabile.jpg\" class=\"vcex-image-img wpex-align-middle\" alt=\"\" loading=\"lazy\" decoding=\"async\" srcset=\"https:\/\/volumec.com\/wp-content\/uploads\/2025\/01\/braccio-articolato-bloccabile.jpg 800w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/01\/braccio-articolato-bloccabile-300x132.jpg 300w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/01\/braccio-articolato-bloccabile-768x338.jpg 768w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/01\/braccio-articolato-bloccabile-600x264.jpg 600w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/div><\/figure>[\/vc_column][\/vc_row][vc_row el_class=&#8220;ptd50 pbd50 ptm50 pbm50&#8243;][vc_column][vc_column_text css=&#8220;&#8220; font_weight=&#8220;700&#8243;]\n<h2 style=\"text-align: center;\">VIDEO<\/h2>\n[\/vc_column_text][vc_row_inner][vc_column_inner][vc_video link=&#8220;https:\/\/youtu.be\/mh1PJNqwl0c&#8220; el_width=&#8220;50&#8243; align=&#8220;center&#8220; css=&#8220;&#8220; el_class=&#8220;mtd30 mtm30&#8243;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row el_class=&#8220;mtd70 mtm50&#8243;][vc_column][vc_column_text css=&#8220;&#8220;]\n<h2 style=\"text-align: center;\"><b>WERKZEUGK\u00d6PFE<\/b><\/h2>\n[\/vc_column_text][\/vc_column][\/vc_row][vc_row el_class=&#8220;ptd50 ptm50&#8243;][vc_column width=&#8220;1\/3&#8243;]<style>.vcex-image.vcex_6a57e67cd0544 .vcex-image-img{border-radius:0px;border-color:#00000042;}<\/style><figure class=\"vcex-image vcex-module wpex-text-center vcex_6a57e67cd0544\"><div class=\"vcex-image-inner wpex-relative wpex-inline-block\"><a href=\"https:\/\/volumec.com\/wp-content\/uploads\/2025\/02\/m.jpg\" class=\"wpex-lightbox\"><img width=\"800\" height=\"400\" src=\"https:\/\/volumec.com\/wp-content\/uploads\/2025\/02\/m.jpg\" class=\"vcex-image-img wpex-align-middle wpex-border wpex-border-solid\" alt=\"\" loading=\"lazy\" decoding=\"async\" srcset=\"https:\/\/volumec.com\/wp-content\/uploads\/2025\/02\/m.jpg 800w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/02\/m-300x150.jpg 300w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/02\/m-768x384.jpg 768w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/02\/m-600x300.jpg 600w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/div><\/figure>[vc_column_text css=&#8220;&#8220; font_size=&#8220;19px&#8220; line_height=&#8220;100%&#8220; font_weight=&#8220;700&#8243; el_class=&#8220;mtd20 mtm20&#8243;]\n<p class=\"mb-2\">M<\/p>\n[\/vc_column_text][vc_column_text css=&#8220;&#8220; el_class=&#8220;mtd15 mtm15&#8243;]Der multidirektionale Kopf ist in verschiedenen Winkeln einstellbar und arretierbar.<br \/>\nMax 8Kg[\/vc_column_text][\/vc_column][vc_column width=&#8220;1\/3&#8243; el_class=&#8220;mtm40&#8243;]<style>.vcex-image.vcex_6a57e67cd21a6 .vcex-image-img{border-radius:0px;border-color:#00000042;}<\/style><figure class=\"vcex-image vcex-module wpex-text-center vcex_6a57e67cd21a6\"><div class=\"vcex-image-inner wpex-relative wpex-inline-block\"><a href=\"https:\/\/volumec.com\/wp-content\/uploads\/2025\/02\/m-1.jpg\" class=\"wpex-lightbox\"><img width=\"800\" height=\"400\" src=\"https:\/\/volumec.com\/wp-content\/uploads\/2025\/02\/m-1.jpg\" class=\"vcex-image-img wpex-align-middle wpex-border wpex-border-solid\" alt=\"\" loading=\"lazy\" decoding=\"async\" srcset=\"https:\/\/volumec.com\/wp-content\/uploads\/2025\/02\/m-1.jpg 800w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/02\/m-1-300x150.jpg 300w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/02\/m-1-768x384.jpg 768w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/02\/m-1-600x300.jpg 600w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/div><\/figure>[vc_column_text css=&#8220;&#8220; font_size=&#8220;19px&#8220; line_height=&#8220;100%&#8220; font_weight=&#8220;700&#8243; el_class=&#8220;mtd20 mtm20&#8243;]\n<p class=\"mb-2\">M1<\/p>\n[\/vc_column_text][vc_column_text css=&#8220;&#8220; el_class=&#8220;mtd15 mtm15&#8243;]Verst\u00e4rkter multidirektionaler Kopf, der in verschiedenen Winkeln einstellbar und arretierbar ist.<br \/>\nMax 14Kg[\/vc_column_text][\/vc_column][vc_column width=&#8220;1\/3&#8243; el_class=&#8220;mtm40&#8243;]<style>.vcex-image.vcex_6a57e67cd3e10 .vcex-image-img{border-radius:0px;border-color:#00000042;}<\/style><figure class=\"vcex-image vcex-module wpex-text-center vcex_6a57e67cd3e10\"><div class=\"vcex-image-inner wpex-relative wpex-inline-block\"><a href=\"https:\/\/volumec.com\/wp-content\/uploads\/2025\/02\/FRH0-90-1.jpg\" class=\"wpex-lightbox\"><img width=\"800\" height=\"400\" src=\"https:\/\/volumec.com\/wp-content\/uploads\/2025\/02\/FRH0-90-1.jpg\" class=\"vcex-image-img wpex-align-middle wpex-border wpex-border-solid\" alt=\"\" loading=\"lazy\" decoding=\"async\" srcset=\"https:\/\/volumec.com\/wp-content\/uploads\/2025\/02\/FRH0-90-1.jpg 800w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/02\/FRH0-90-1-300x150.jpg 300w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/02\/FRH0-90-1-768x384.jpg 768w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/02\/FRH0-90-1-600x300.jpg 600w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/div><\/figure>[vc_column_text css=&#8220;&#8220; font_size=&#8220;19px&#8220; line_height=&#8220;100%&#8220; font_weight=&#8220;700&#8243; el_class=&#8220;mtd20 mtm20&#8243;]\n<p class=\"mb-2\">FRH0-90<\/p>\n[\/vc_column_text][vc_column_text css=&#8220;&#8220; el_class=&#8220;mtd15 mtm15&#8243;]Schnellpositionierkopf 0\u00b0-90\u00b0 &#8211; OHNE WERKZEUGMONTAGEKLEMME (T).[\/vc_column_text][\/vc_column][\/vc_row][vc_row el_class=&#8220;ptd50 ptm50&#8243;][vc_column width=&#8220;1\/2&#8243;]<style>.vcex-image.vcex_6a57e67cd5a96 .vcex-image-img{border-radius:0px;border-color:#00000042;}<\/style><figure class=\"vcex-image vcex-module wpex-text-center vcex_6a57e67cd5a96\"><div class=\"vcex-image-inner wpex-relative wpex-inline-block\"><a href=\"https:\/\/volumec.com\/wp-content\/uploads\/2025\/02\/T40-T60-T80-1.jpg\" class=\"wpex-lightbox\"><img width=\"800\" height=\"400\" src=\"https:\/\/volumec.com\/wp-content\/uploads\/2025\/02\/T40-T60-T80-1.jpg\" class=\"vcex-image-img wpex-align-middle wpex-border wpex-border-solid\" alt=\"\" loading=\"lazy\" decoding=\"async\" srcset=\"https:\/\/volumec.com\/wp-content\/uploads\/2025\/02\/T40-T60-T80-1.jpg 800w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/02\/T40-T60-T80-1-300x150.jpg 300w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/02\/T40-T60-T80-1-768x384.jpg 768w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/02\/T40-T60-T80-1-600x300.jpg 600w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/div><\/figure>[vc_column_text css=&#8220;&#8220; font_size=&#8220;19px&#8220; line_height=&#8220;100%&#8220; font_weight=&#8220;700&#8243; el_class=&#8220;mtd20 mtm20&#8243;]\n<p class=\"mb-2\">T40-T60-T80<\/p>\n[\/vc_column_text][vc_column_text css=&#8220;&#8220; el_class=&#8220;mtd15 mtm15&#8243;]Klemme f\u00fcr Werkzeugbefestigung &#8211; Durchmesser 40 &#8211; 60 &#8211; 80 mm[\/vc_column_text][\/vc_column][vc_column width=&#8220;1\/2&#8243; el_class=&#8220;mtm40&#8243;]<style>.vcex-image.vcex_6a57e67cd76fa .vcex-image-img{border-radius:0px;border-color:#00000042;}<\/style><figure class=\"vcex-image vcex-module wpex-text-center vcex_6a57e67cd76fa\"><div class=\"vcex-image-inner wpex-relative wpex-inline-block\"><a href=\"https:\/\/volumec.com\/wp-content\/uploads\/2025\/02\/A40-A60-A80-1.jpg\" class=\"wpex-lightbox\"><img width=\"800\" height=\"400\" src=\"https:\/\/volumec.com\/wp-content\/uploads\/2025\/02\/A40-A60-A80-1.jpg\" class=\"vcex-image-img wpex-align-middle wpex-border wpex-border-solid\" alt=\"\" loading=\"lazy\" decoding=\"async\" srcset=\"https:\/\/volumec.com\/wp-content\/uploads\/2025\/02\/A40-A60-A80-1.jpg 800w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/02\/A40-A60-A80-1-300x150.jpg 300w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/02\/A40-A60-A80-1-768x384.jpg 768w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/02\/A40-A60-A80-1-600x300.jpg 600w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/div><\/figure>[vc_column_text css=&#8220;&#8220; font_size=&#8220;19px&#8220; line_height=&#8220;100%&#8220; font_weight=&#8220;700&#8243; el_class=&#8220;mtd20 mtm20&#8243;]\n<p class=\"mb-2\">A40-A60-A80<\/p>\n[\/vc_column_text][vc_column_text css=&#8220;&#8220; el_class=&#8220;mtd15 mtm15&#8243;]Adapter f\u00fcr Durchmesser unter 40-60-80 mm[\/vc_column_text][\/vc_column][\/vc_row][vc_row content_placement=&#8220;middle&#8220; el_class=&#8220;mtd70 mtm50&#8243;][vc_column width=&#8220;2\/3&#8243;][vc_column_text css=&#8220;&#8220; text_align=&#8220;center&#8220; text_transform=&#8220;uppercase&#8220;]\n<h2><strong>ORBITALAUFS\u00c4TZE<\/strong><\/h2>\n[\/vc_column_text][vc_column_text css=&#8220;&#8220; el_class=&#8220;mtd20 mtm20 mbd20 mbm20&#8243; text_align=&#8220;center&#8220;]Easyarm bietet eine komplette Reihe von K\u00f6pfen zur Befestigung von Werkzeugen oder Vorrichtungen, die je nach Art der durchzuf\u00fchrenden Bearbeitung ausgew\u00e4hlt werden k\u00f6nnen.<br \/>\nDie neue Linie der drehbaren Orbitalaufs\u00e4tze bietet maximale Vielseitigkeit bei der Auswahl mit dem Vorteil, dass das Werkzeug je nach dem zu erreichenden Arbeitsbereich sowohl nach oben als auch nach unten positioniert werden kann.[\/vc_column_text][\/vc_column][vc_column width=&#8220;1\/3&#8243;]<figure class=\"vcex-image vcex-module wpex-text-center mtd30 mtm20\"><div class=\"vcex-image-inner wpex-relative wpex-inline-block\"><img width=\"820\" height=\"820\" src=\"https:\/\/volumec.com\/wp-content\/uploads\/2025\/01\/revolving.png\" class=\"vcex-image-img wpex-align-middle\" alt=\"\" loading=\"lazy\" decoding=\"async\" srcset=\"https:\/\/volumec.com\/wp-content\/uploads\/2025\/01\/revolving.png 820w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/01\/revolving-300x300.png 300w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/01\/revolving-150x150.png 150w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/01\/revolving-768x768.png 768w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/01\/revolving-600x600.png 600w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/01\/revolving-100x100.png 100w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/01\/revolving-460x460.png 460w\" sizes=\"auto, (max-width: 820px) 100vw, 820px\" \/><\/div><\/figure>[\/vc_column][\/vc_row][vc_row el_class=&#8220;ptd50 ptm50&#8243;][vc_column width=&#8220;1\/4&#8243;]<style>.vcex-image.vcex_6a57e67cdaf22 .vcex-image-img{border-radius:0px;border-color:#00000042;}<\/style><figure class=\"vcex-image vcex-module wpex-text-center vcex_6a57e67cdaf22\"><div class=\"vcex-image-inner wpex-relative wpex-inline-block\"><a href=\"https:\/\/volumec.com\/wp-content\/uploads\/2025\/02\/A0.jpg\" class=\"wpex-lightbox\"><img width=\"800\" height=\"400\" src=\"https:\/\/volumec.com\/wp-content\/uploads\/2025\/02\/A0.jpg\" class=\"vcex-image-img wpex-align-middle wpex-border wpex-border-solid\" alt=\"\" loading=\"lazy\" decoding=\"async\" srcset=\"https:\/\/volumec.com\/wp-content\/uploads\/2025\/02\/A0.jpg 800w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/02\/A0-300x150.jpg 300w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/02\/A0-768x384.jpg 768w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/02\/A0-600x300.jpg 600w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/div><\/figure>[vc_column_text css=&#8220;&#8220; font_size=&#8220;19px&#8220; line_height=&#8220;100%&#8220; font_weight=&#8220;700&#8243; el_class=&#8220;mtd20 mtm20&#8243;]\n<p class=\"mb-2\">A0<\/p>\n[\/vc_column_text][vc_column_text css=&#8220;&#8220; el_class=&#8220;mtd15 mtm15&#8243; font_size=&#8220;13px&#8220;]ORBITALAUFSATZ[\/vc_column_text][\/vc_column][vc_column width=&#8220;1\/4&#8243; el_class=&#8220;mtm40&#8243;]<style>.vcex-image.vcex_6a57e67cdcbae .vcex-image-img{border-radius:0px;border-color:#00000042;}<\/style><figure class=\"vcex-image vcex-module wpex-text-center vcex_6a57e67cdcbae\"><div class=\"vcex-image-inner wpex-relative wpex-inline-block\"><a href=\"https:\/\/volumec.com\/wp-content\/uploads\/2025\/01\/A1.jpg\" class=\"wpex-lightbox\"><img width=\"800\" height=\"400\" src=\"https:\/\/volumec.com\/wp-content\/uploads\/2025\/01\/A1.jpg\" class=\"vcex-image-img wpex-align-middle wpex-border wpex-border-solid\" alt=\"\" loading=\"lazy\" decoding=\"async\" srcset=\"https:\/\/volumec.com\/wp-content\/uploads\/2025\/01\/A1.jpg 800w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/01\/A1-300x150.jpg 300w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/01\/A1-768x384.jpg 768w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/01\/A1-600x300.jpg 600w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/div><\/figure>[vc_column_text css=&#8220;&#8220; font_size=&#8220;19px&#8220; line_height=&#8220;100%&#8220; font_weight=&#8220;700&#8243; el_class=&#8220;mtd20 mtm20&#8243;]\n<p class=\"mb-2\">A1<\/p>\n[\/vc_column_text][vc_column_text css=&#8220;&#8220; el_class=&#8220;mtd15 mtm15&#8243; font_size=&#8220;13px&#8220;]ORBITALAUFSATZ[\/vc_column_text][\/vc_column][vc_column width=&#8220;1\/4&#8243; el_class=&#8220;mtm40&#8243;]<style>.vcex-image.vcex_6a57e67cde860 .vcex-image-img{border-radius:0px;border-color:#00000042;}<\/style><figure class=\"vcex-image vcex-module wpex-text-center vcex_6a57e67cde860\"><div class=\"vcex-image-inner wpex-relative wpex-inline-block\"><a href=\"https:\/\/volumec.com\/wp-content\/uploads\/2025\/01\/A2.jpg\" class=\"wpex-lightbox\"><img width=\"800\" height=\"400\" src=\"https:\/\/volumec.com\/wp-content\/uploads\/2025\/01\/A2.jpg\" class=\"vcex-image-img wpex-align-middle wpex-border wpex-border-solid\" alt=\"\" loading=\"lazy\" decoding=\"async\" srcset=\"https:\/\/volumec.com\/wp-content\/uploads\/2025\/01\/A2.jpg 800w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/01\/A2-300x150.jpg 300w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/01\/A2-768x384.jpg 768w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/01\/A2-600x300.jpg 600w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/div><\/figure>[vc_column_text css=&#8220;&#8220; font_size=&#8220;19px&#8220; line_height=&#8220;100%&#8220; font_weight=&#8220;700&#8243; el_class=&#8220;mtd20 mtm20&#8243;]\n<p class=\"mb-2\">A2<\/p>\n[\/vc_column_text][vc_column_text css=&#8220;&#8220; el_class=&#8220;mtd15 mtm15&#8243; font_size=&#8220;13px&#8220;]ORBITALAUFSATZ OHNE KLEMME F\u00dcR WERKZEUGAUFSATZ (T)[\/vc_column_text][\/vc_column][vc_column width=&#8220;1\/4&#8243;]<style>.vcex-image.vcex_6a57e67ce04e0 .vcex-image-img{border-radius:0px;border-color:#00000042;}<\/style><figure class=\"vcex-image vcex-module wpex-text-center vcex_6a57e67ce04e0\"><div class=\"vcex-image-inner wpex-relative wpex-inline-block\"><a href=\"https:\/\/volumec.com\/wp-content\/uploads\/2025\/01\/A3.jpg\" class=\"wpex-lightbox\"><img width=\"800\" height=\"400\" src=\"https:\/\/volumec.com\/wp-content\/uploads\/2025\/01\/A3.jpg\" class=\"vcex-image-img wpex-align-middle wpex-border wpex-border-solid\" alt=\"\" loading=\"lazy\" decoding=\"async\" srcset=\"https:\/\/volumec.com\/wp-content\/uploads\/2025\/01\/A3.jpg 800w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/01\/A3-300x150.jpg 300w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/01\/A3-768x384.jpg 768w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/01\/A3-600x300.jpg 600w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/div><\/figure>[vc_column_text css=&#8220;&#8220; font_size=&#8220;19px&#8220; line_height=&#8220;100%&#8220; font_weight=&#8220;700&#8243; el_class=&#8220;mtd20 mtm20&#8243;]\n<p class=\"mb-2\">A3<\/p>\n[\/vc_column_text][vc_column_text css=&#8220;&#8220; el_class=&#8220;mtd15 mtm15&#8243; font_size=&#8220;13px&#8220;]ORBITALAUFSATZ OHNE KLEMME F\u00dcR WERKZEUGAUFSATZ (T)[\/vc_column_text][\/vc_column][\/vc_row][vc_row el_class=&#8220;ptd40 mtm40&#8243;][vc_column width=&#8220;1\/4&#8243; el_class=&#8220;mtm40&#8243;]<style>.vcex-image.vcex_6a57e67ce2110 .vcex-image-img{border-radius:0px;border-color:#00000042;}<\/style><figure class=\"vcex-image vcex-module wpex-text-center vcex_6a57e67ce2110\"><div class=\"vcex-image-inner wpex-relative wpex-inline-block\"><a href=\"https:\/\/volumec.com\/wp-content\/uploads\/2025\/01\/A4.jpg\" class=\"wpex-lightbox\"><img width=\"800\" height=\"400\" src=\"https:\/\/volumec.com\/wp-content\/uploads\/2025\/01\/A4.jpg\" class=\"vcex-image-img wpex-align-middle wpex-border wpex-border-solid\" alt=\"\" loading=\"lazy\" decoding=\"async\" srcset=\"https:\/\/volumec.com\/wp-content\/uploads\/2025\/01\/A4.jpg 800w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/01\/A4-300x150.jpg 300w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/01\/A4-768x384.jpg 768w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/01\/A4-600x300.jpg 600w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/div><\/figure>[vc_column_text css=&#8220;&#8220; font_size=&#8220;19px&#8220; line_height=&#8220;100%&#8220; font_weight=&#8220;700&#8243; el_class=&#8220;mtd20 mtm20&#8243;]\n<p class=\"mb-2\">A4<\/p>\n[\/vc_column_text][vc_column_text css=&#8220;&#8220; el_class=&#8220;mtd15 mtm15&#8243; font_size=&#8220;13px&#8220;]ORBITALAUFSATZ[\/vc_column_text][\/vc_column][vc_column width=&#8220;1\/4&#8243; el_class=&#8220;mtm40&#8243;]<style>.vcex-image.vcex_6a57e67ce3d29 .vcex-image-img{border-radius:0px;border-color:#00000042;}<\/style><figure class=\"vcex-image vcex-module wpex-text-center vcex_6a57e67ce3d29\"><div class=\"vcex-image-inner wpex-relative wpex-inline-block\"><a href=\"https:\/\/volumec.com\/wp-content\/uploads\/2025\/01\/B1.jpg\" class=\"wpex-lightbox\"><img width=\"800\" height=\"400\" src=\"https:\/\/volumec.com\/wp-content\/uploads\/2025\/01\/B1.jpg\" class=\"vcex-image-img wpex-align-middle wpex-border wpex-border-solid\" alt=\"\" loading=\"lazy\" decoding=\"async\" srcset=\"https:\/\/volumec.com\/wp-content\/uploads\/2025\/01\/B1.jpg 800w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/01\/B1-300x150.jpg 300w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/01\/B1-768x384.jpg 768w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/01\/B1-600x300.jpg 600w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/div><\/figure>[vc_column_text css=&#8220;&#8220; font_size=&#8220;19px&#8220; line_height=&#8220;100%&#8220; font_weight=&#8220;700&#8243; el_class=&#8220;mtd20 mtm20&#8243;]\n<p class=\"mb-2\">B1<\/p>\n[\/vc_column_text][vc_column_text css=&#8220;&#8220; el_class=&#8220;mtd15 mtm15&#8243; font_size=&#8220;13px&#8220;]ORBITALAUFSATZ[\/vc_column_text][\/vc_column][vc_column width=&#8220;1\/4&#8243;]<style>.vcex-image.vcex_6a57e67ce5985 .vcex-image-img{border-radius:0px;border-color:#00000042;}<\/style><figure class=\"vcex-image vcex-module wpex-text-center vcex_6a57e67ce5985\"><div class=\"vcex-image-inner wpex-relative wpex-inline-block\"><a href=\"https:\/\/volumec.com\/wp-content\/uploads\/2025\/01\/C1.jpg\" class=\"wpex-lightbox\"><img width=\"800\" height=\"400\" src=\"https:\/\/volumec.com\/wp-content\/uploads\/2025\/01\/C1.jpg\" class=\"vcex-image-img wpex-align-middle wpex-border wpex-border-solid\" alt=\"\" loading=\"lazy\" decoding=\"async\" srcset=\"https:\/\/volumec.com\/wp-content\/uploads\/2025\/01\/C1.jpg 800w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/01\/C1-300x150.jpg 300w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/01\/C1-768x384.jpg 768w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/01\/C1-600x300.jpg 600w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/div><\/figure>[vc_column_text css=&#8220;&#8220; font_size=&#8220;19px&#8220; line_height=&#8220;100%&#8220; font_weight=&#8220;700&#8243; el_class=&#8220;mtd20 mtm20&#8243;]\n<p class=\"mb-2\">C1<\/p>\n[\/vc_column_text][vc_column_text css=&#8220;&#8220; el_class=&#8220;mtd15 mtm15&#8243; font_size=&#8220;13px&#8220;]MAXIMALER ORBITALER WERKZEUG-DURCHMESSER 125 mm[\/vc_column_text][\/vc_column][vc_column width=&#8220;1\/4&#8243;]<style>.vcex-image.vcex_6a57e67ce75fa .vcex-image-img{border-radius:0px;border-color:#00000042;}<\/style><figure class=\"vcex-image vcex-module wpex-text-center vcex_6a57e67ce75fa\"><div class=\"vcex-image-inner wpex-relative wpex-inline-block\"><a href=\"https:\/\/volumec.com\/wp-content\/uploads\/2025\/01\/C2.jpg\" class=\"wpex-lightbox\"><img width=\"800\" height=\"400\" src=\"https:\/\/volumec.com\/wp-content\/uploads\/2025\/01\/C2.jpg\" class=\"vcex-image-img wpex-align-middle wpex-border wpex-border-solid\" alt=\"\" loading=\"lazy\" decoding=\"async\" srcset=\"https:\/\/volumec.com\/wp-content\/uploads\/2025\/01\/C2.jpg 800w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/01\/C2-300x150.jpg 300w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/01\/C2-768x384.jpg 768w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/01\/C2-600x300.jpg 600w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/div><\/figure>[vc_column_text css=&#8220;&#8220; font_size=&#8220;19px&#8220; line_height=&#8220;100%&#8220; font_weight=&#8220;700&#8243; el_class=&#8220;mtd20 mtm20&#8243;]\n<p class=\"mb-2\">C2<\/p>\n[\/vc_column_text][vc_column_text css=&#8220;&#8220; el_class=&#8220;mtd15 mtm15&#8243; font_size=&#8220;13px&#8220;]MAXIMALER ORBITALER WERKZEUG-DURCHMESSER 125 mm[\/vc_column_text][\/vc_column][\/vc_row][vc_row el_class=&#8220;ptd40 mtm40&#8243;][vc_column width=&#8220;1\/4&#8243;]<style>.vcex-image.vcex_6a57e67ce9274 .vcex-image-img{border-radius:0px;border-color:#00000042;}<\/style><figure class=\"vcex-image vcex-module wpex-text-center vcex_6a57e67ce9274\"><div class=\"vcex-image-inner wpex-relative wpex-inline-block\"><a href=\"https:\/\/volumec.com\/wp-content\/uploads\/2025\/01\/D1.jpg\" class=\"wpex-lightbox\"><img width=\"800\" height=\"400\" src=\"https:\/\/volumec.com\/wp-content\/uploads\/2025\/01\/D1.jpg\" class=\"vcex-image-img wpex-align-middle wpex-border wpex-border-solid\" alt=\"\" loading=\"lazy\" decoding=\"async\" srcset=\"https:\/\/volumec.com\/wp-content\/uploads\/2025\/01\/D1.jpg 800w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/01\/D1-300x150.jpg 300w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/01\/D1-768x384.jpg 768w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/01\/D1-600x300.jpg 600w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/div><\/figure>[vc_column_text css=&#8220;&#8220; font_size=&#8220;19px&#8220; line_height=&#8220;100%&#8220; font_weight=&#8220;700&#8243; el_class=&#8220;mtd20 mtm20&#8243;]D1[\/vc_column_text][vc_column_text css=&#8220;&#8220; el_class=&#8220;mtd15 mtm15&#8243; font_size=&#8220;13px&#8220;]ORBITALER ANSATZ MAXIMALER WERKZEUGDURCHMESSER 85 mm[\/vc_column_text][\/vc_column][vc_column width=&#8220;1\/4&#8243;]<style>.vcex-image.vcex_6a57e67ceaf10 .vcex-image-img{border-radius:0px;border-color:#00000042;}<\/style><figure class=\"vcex-image vcex-module wpex-text-center vcex_6a57e67ceaf10\"><div class=\"vcex-image-inner wpex-relative wpex-inline-block\"><a href=\"https:\/\/volumec.com\/wp-content\/uploads\/2025\/01\/D2.jpg\" class=\"wpex-lightbox\"><img width=\"800\" height=\"400\" src=\"https:\/\/volumec.com\/wp-content\/uploads\/2025\/01\/D2.jpg\" class=\"vcex-image-img wpex-align-middle wpex-border wpex-border-solid\" alt=\"\" loading=\"lazy\" decoding=\"async\" srcset=\"https:\/\/volumec.com\/wp-content\/uploads\/2025\/01\/D2.jpg 800w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/01\/D2-300x150.jpg 300w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/01\/D2-768x384.jpg 768w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/01\/D2-600x300.jpg 600w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/div><\/figure>[vc_column_text css=&#8220;&#8220; font_size=&#8220;19px&#8220; line_height=&#8220;100%&#8220; font_weight=&#8220;700&#8243; el_class=&#8220;mtd20 mtm20&#8243;]\n<p class=\"mb-2\">D2<\/p>\n[\/vc_column_text][vc_column_text css=&#8220;&#8220; el_class=&#8220;mtd15 mtm15&#8243; font_size=&#8220;13px&#8220;]ORBITALER ANSATZ MAXIMALER WERKZEUGDURCHMESSER 85 mm[\/vc_column_text][\/vc_column][vc_column width=&#8220;1\/4&#8243;]<style>.vcex-image.vcex_6a57e67cecb7b .vcex-image-img{border-radius:0px;border-color:#00000042;}<\/style><figure class=\"vcex-image vcex-module wpex-text-center vcex_6a57e67cecb7b\"><div class=\"vcex-image-inner wpex-relative wpex-inline-block\"><a href=\"https:\/\/volumec.com\/wp-content\/uploads\/2025\/01\/E.jpg\" class=\"wpex-lightbox\"><img width=\"800\" height=\"400\" src=\"https:\/\/volumec.com\/wp-content\/uploads\/2025\/01\/E.jpg\" class=\"vcex-image-img wpex-align-middle wpex-border wpex-border-solid\" alt=\"\" loading=\"lazy\" decoding=\"async\" srcset=\"https:\/\/volumec.com\/wp-content\/uploads\/2025\/01\/E.jpg 800w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/01\/E-300x150.jpg 300w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/01\/E-768x384.jpg 768w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/01\/E-600x300.jpg 600w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/div><\/figure>[vc_column_text css=&#8220;&#8220; font_size=&#8220;19px&#8220; line_height=&#8220;100%&#8220; font_weight=&#8220;700&#8243; el_class=&#8220;mtd20 mtm20&#8243;]\n<p class=\"mb-2\">E<\/p>\n[\/vc_column_text][vc_column_text css=&#8220;&#8220; el_class=&#8220;mtd15 mtm15&#8243; font_size=&#8220;13px&#8220;]ORBITALER ANSATZ MIT WERKZEUG ADAPTER COUPLE MAXIMALER WERKZEUGDURCHMESSER 70 mm[\/vc_column_text][\/vc_column][vc_column width=&#8220;1\/4&#8243;]<style>.vcex-image.vcex_6a57e67cee80b .vcex-image-img{border-radius:0px;border-color:#00000042;}<\/style><figure class=\"vcex-image vcex-module wpex-text-center vcex_6a57e67cee80b\"><div class=\"vcex-image-inner wpex-relative wpex-inline-block\"><a href=\"https:\/\/volumec.com\/wp-content\/uploads\/2025\/01\/G1.jpg\" class=\"wpex-lightbox\"><img width=\"800\" height=\"400\" src=\"https:\/\/volumec.com\/wp-content\/uploads\/2025\/01\/G1.jpg\" class=\"vcex-image-img wpex-align-middle wpex-border wpex-border-solid\" alt=\"\" loading=\"lazy\" decoding=\"async\" srcset=\"https:\/\/volumec.com\/wp-content\/uploads\/2025\/01\/G1.jpg 800w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/01\/G1-300x150.jpg 300w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/01\/G1-768x384.jpg 768w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/01\/G1-600x300.jpg 600w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/div><\/figure>[vc_column_text css=&#8220;&#8220; font_size=&#8220;19px&#8220; line_height=&#8220;100%&#8220; font_weight=&#8220;700&#8243; el_class=&#8220;mtd20 mtm20&#8243;]\n<p class=\"mb-2\">G1<\/p>\n[\/vc_column_text][vc_column_text css=&#8220;&#8220; el_class=&#8220;mtd15 mtm15&#8243; font_size=&#8220;13px&#8220;]ORBITALER ANSATZ MAXIMALER WERKZEUGDURCHMESSER 85 mm[\/vc_column_text][\/vc_column][\/vc_row][vc_row el_class=&#8220;ptd40 mtm40&#8243;][vc_column width=&#8220;1\/4&#8243; css=&#8220;.vc_custom_1748589063526{margin-bottom: 70px !important;}&#8220;]<style>.vcex-image.vcex_6a57e67cf046e .vcex-image-img{border-radius:0px;border-color:#00000042;}<\/style><figure class=\"vcex-image vcex-module wpex-text-center vcex_6a57e67cf046e\"><div class=\"vcex-image-inner wpex-relative wpex-inline-block\"><a href=\"https:\/\/volumec.com\/wp-content\/uploads\/2025\/01\/G2.jpg\" class=\"wpex-lightbox\"><img width=\"800\" height=\"400\" src=\"https:\/\/volumec.com\/wp-content\/uploads\/2025\/01\/G2.jpg\" class=\"vcex-image-img wpex-align-middle wpex-border wpex-border-solid\" alt=\"\" loading=\"lazy\" decoding=\"async\" srcset=\"https:\/\/volumec.com\/wp-content\/uploads\/2025\/01\/G2.jpg 800w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/01\/G2-300x150.jpg 300w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/01\/G2-768x384.jpg 768w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/01\/G2-600x300.jpg 600w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/div><\/figure>[vc_column_text css=&#8220;&#8220; font_size=&#8220;19px&#8220; line_height=&#8220;100%&#8220; font_weight=&#8220;700&#8243; el_class=&#8220;mtd20 mtm20&#8243;]\n<p class=\"mb-2\">G2<\/p>\n[\/vc_column_text][vc_column_text css=&#8220;&#8220; el_class=&#8220;mtd15 mtm15&#8243; font_size=&#8220;13px&#8220;]ATTACCO ORBITALE MASSIMO DIAMETRO UTENSILE 125 mm[\/vc_column_text][\/vc_column][vc_column width=&#8220;1\/4&#8243;][\/vc_column][vc_column width=&#8220;1\/4&#8243;][\/vc_column][vc_column width=&#8220;1\/4&#8243;][\/vc_column][\/vc_row][vc_row full_width=&#8220;stretch_row&#8220; local_scroll_id=&#8220;info&#8220; css=&#8220;.vc_custom_1740392980023{margin-bottom: -35px !important;background-color: #F1F1F1 !important;}&#8220; el_class=&#8220;ptd50 ptm50 pbd50 pbm50&#8243;][vc_column][vc_column_text css=&#8220;&#8220;]\n<h2 style=\"text-align: center;\"><strong>OPTIONAL<\/strong><\/h2>\n[\/vc_column_text][\/vc_column][\/vc_row][vc_row full_width=&#8220;stretch_row&#8220; el_class=&#8220;ptd40 mtm40&#8243; css=&#8220;.vc_custom_1740391977983{background-color: #F1F1F1 !important;}&#8220;][vc_column width=&#8220;1\/4&#8243; el_class=&#8220;mtm40&#8243;]<style>.vcex-image.vcex_6a57e67cf2120 .vcex-image-img{border-radius:0px;border-color:#00000042;}<\/style><figure class=\"vcex-image vcex-module wpex-text-center vcex_6a57e67cf2120\"><div class=\"vcex-image-inner wpex-relative wpex-inline-block\"><a href=\"https:\/\/volumec.com\/wp-content\/uploads\/2025\/02\/mca001.jpg\" class=\"wpex-lightbox\"><img width=\"800\" height=\"800\" src=\"https:\/\/volumec.com\/wp-content\/uploads\/2025\/02\/mca001.jpg\" class=\"vcex-image-img wpex-align-middle wpex-border wpex-border-solid\" alt=\"\" loading=\"lazy\" decoding=\"async\" srcset=\"https:\/\/volumec.com\/wp-content\/uploads\/2025\/02\/mca001.jpg 800w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/02\/mca001-300x300.jpg 300w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/02\/mca001-150x150.jpg 150w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/02\/mca001-768x768.jpg 768w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/02\/mca001-600x600.jpg 600w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/02\/mca001-100x100.jpg 100w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/02\/mca001-460x460.jpg 460w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/div><\/figure>[vc_column_text css=&#8220;&#8220; font_size=&#8220;19px&#8220; line_height=&#8220;100%&#8220; font_weight=&#8220;700&#8243; el_class=&#8220;mtd20 mtm20&#8243;]\n<p class=\"mb-2\">(MCA001) TROLLEY 850X750 H=870 mm<\/p>\n[\/vc_column_text][vc_column_text css=&#8220;&#8220; el_class=&#8220;mtd15 mtm15&#8243; font_size=&#8220;13px&#8220;]Aus lackiertem Stahl mit Stauraum f\u00fcr Werkzeuge 4 drehbare R\u00e4der, 2 mit Bremse.<br \/>\nGewicht 65 kg[\/vc_column_text][\/vc_column][vc_column width=&#8220;1\/4&#8243;]<style>.vcex-image.vcex_6a57e67cf3dc4 .vcex-image-img{border-radius:0px;border-color:#00000042;}<\/style><figure class=\"vcex-image vcex-module wpex-text-center vcex_6a57e67cf3dc4\"><div class=\"vcex-image-inner wpex-relative wpex-inline-block\"><a href=\"https:\/\/volumec.com\/wp-content\/uploads\/2025\/02\/cpa001.jpg\" class=\"wpex-lightbox\"><img width=\"457\" height=\"457\" src=\"https:\/\/volumec.com\/wp-content\/uploads\/2025\/02\/cpa001.jpg\" class=\"vcex-image-img wpex-align-middle wpex-border wpex-border-solid\" alt=\"\" loading=\"lazy\" decoding=\"async\" srcset=\"https:\/\/volumec.com\/wp-content\/uploads\/2025\/02\/cpa001.jpg 457w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/02\/cpa001-300x300.jpg 300w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/02\/cpa001-150x150.jpg 150w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/02\/cpa001-100x100.jpg 100w\" sizes=\"auto, (max-width: 457px) 100vw, 457px\" \/><\/a><\/div><\/figure>[vc_column_text css=&#8220;&#8220; font_size=&#8220;19px&#8220; line_height=&#8220;100%&#8220; font_weight=&#8220;700&#8243; el_class=&#8220;mtd20 mtm20&#8243;](CPA001) WAGEN MIT ALUMINIUM-STRUKTURPLAN[\/vc_column_text][vc_column_text css=&#8220;&#8220; el_class=&#8220;mtd15 mtm15&#8243; font_size=&#8220;13px&#8220;]Mit H\u00f6hlen f\u00fcr Klemmst\u00fccke 800&#215;640 h=870 mm<br \/>\nUntere Ablage aus Stahl, 4 drehbare R\u00e4der, 2 mit Bremsen.<br \/>\nGewicht : 55 Kg[\/vc_column_text][\/vc_column][vc_column width=&#8220;1\/4&#8243;]<style>.vcex-image.vcex_6a57e67d017ec .vcex-image-img{border-radius:0px;border-color:#00000042;}<\/style><figure class=\"vcex-image vcex-module wpex-text-center vcex_6a57e67d017ec\"><div class=\"vcex-image-inner wpex-relative wpex-inline-block\"><a href=\"https:\/\/volumec.com\/wp-content\/uploads\/2025\/02\/ccf100.jpg\" class=\"wpex-lightbox\"><img width=\"800\" height=\"800\" src=\"https:\/\/volumec.com\/wp-content\/uploads\/2025\/02\/ccf100.jpg\" class=\"vcex-image-img wpex-align-middle wpex-border wpex-border-solid\" alt=\"\" loading=\"lazy\" decoding=\"async\" srcset=\"https:\/\/volumec.com\/wp-content\/uploads\/2025\/02\/ccf100.jpg 800w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/02\/ccf100-300x300.jpg 300w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/02\/ccf100-150x150.jpg 150w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/02\/ccf100-768x768.jpg 768w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/02\/ccf100-600x600.jpg 600w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/02\/ccf100-100x100.jpg 100w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/02\/ccf100-460x460.jpg 460w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/div><\/figure>[vc_column_text css=&#8220;&#8220; font_size=&#8220;19px&#8220; line_height=&#8220;100%&#8220; font_weight=&#8220;700&#8243; el_class=&#8220;mtd20 mtm20&#8243;]\n<p class=\"mb-2\">(CCF100) TROLLEY 800X800 mm<\/p>\n[\/vc_column_text][vc_column_text css=&#8220;&#8220; el_class=&#8220;mtd15 mtm15&#8243; font_size=&#8220;13px&#8220;]Mit Sockel von 30 mm<br \/>\nMittels\u00e4ule f\u00fcr Armst\u00fctze h=1000 mm<br \/>\n4 drehbare R\u00e4der, 2 mit Bremsen<br \/>\nGewicht 165 kg[\/vc_column_text][\/vc_column][vc_column width=&#8220;1\/4&#8243; el_class=&#8220;mtm40&#8243;]<style>.vcex-image.vcex_6a57e67d03465 .vcex-image-img{border-radius:0px;border-color:#00000042;}<\/style><figure class=\"vcex-image vcex-module wpex-text-center vcex_6a57e67d03465\"><div class=\"vcex-image-inner wpex-relative wpex-inline-block\"><a href=\"https:\/\/volumec.com\/wp-content\/uploads\/2025\/02\/ccf100-1.jpg\" class=\"wpex-lightbox\"><img width=\"800\" height=\"800\" src=\"https:\/\/volumec.com\/wp-content\/uploads\/2025\/02\/ccf100-1.jpg\" class=\"vcex-image-img wpex-align-middle wpex-border wpex-border-solid\" alt=\"\" loading=\"lazy\" decoding=\"async\" srcset=\"https:\/\/volumec.com\/wp-content\/uploads\/2025\/02\/ccf100-1.jpg 800w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/02\/ccf100-1-300x300.jpg 300w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/02\/ccf100-1-150x150.jpg 150w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/02\/ccf100-1-768x768.jpg 768w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/02\/ccf100-1-600x600.jpg 600w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/02\/ccf100-1-100x100.jpg 100w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/02\/ccf100-1-460x460.jpg 460w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/div><\/figure>[vc_column_text css=&#8220;&#8220; font_size=&#8220;19px&#8220; line_height=&#8220;100%&#8220; font_weight=&#8220;700&#8243; el_class=&#8220;mtd20 mtm20&#8243;]\n<p class=\"mb-2\">(CCF100-1) TROLLEY 800X800 mm<\/p>\n[\/vc_column_text][vc_column_text css=&#8220;&#8220; el_class=&#8220;mtd15 mtm15&#8243; font_size=&#8220;13px&#8220;]Mit Sockel von 30 mm, Mittels\u00e4ule f\u00fcr Armst\u00fctze mit einstellbarer H\u00f6he von 650 mm bis 1050 mm, 4 drehbare R\u00e4der, 2 mit Bremsen.<br \/>\nGewicht 165 Kg[\/vc_column_text][\/vc_column][\/vc_row][vc_row full_width=&#8220;stretch_row&#8220; el_class=&#8220;ptd40 mtm40&#8243; css=&#8220;.vc_custom_1740391977983{background-color: #F1F1F1 !important;}&#8220;][vc_column width=&#8220;1\/4&#8243;]<style>.vcex-image.vcex_6a57e67d050f2 .vcex-image-img{border-radius:0px;border-color:#00000042;}<\/style><figure class=\"vcex-image vcex-module wpex-text-center vcex_6a57e67d050f2\"><div class=\"vcex-image-inner wpex-relative wpex-inline-block\"><a href=\"https:\/\/volumec.com\/wp-content\/uploads\/2025\/02\/ccf100-eam.jpg\" class=\"wpex-lightbox\"><img width=\"800\" height=\"800\" src=\"https:\/\/volumec.com\/wp-content\/uploads\/2025\/02\/ccf100-eam.jpg\" class=\"vcex-image-img wpex-align-middle wpex-border wpex-border-solid\" alt=\"\" loading=\"lazy\" decoding=\"async\" srcset=\"https:\/\/volumec.com\/wp-content\/uploads\/2025\/02\/ccf100-eam.jpg 800w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/02\/ccf100-eam-300x300.jpg 300w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/02\/ccf100-eam-150x150.jpg 150w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/02\/ccf100-eam-768x768.jpg 768w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/02\/ccf100-eam-600x600.jpg 600w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/02\/ccf100-eam-100x100.jpg 100w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/02\/ccf100-eam-460x460.jpg 460w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/div><\/figure>[vc_column_text css=&#8220;&#8220; font_size=&#8220;19px&#8220; line_height=&#8220;100%&#8220; font_weight=&#8220;700&#8243; el_class=&#8220;mtd20 mtm20&#8243;](CCF100-EAM) TROLLEY 800X800 mm[\/vc_column_text][vc_column_text css=&#8220;&#8220; el_class=&#8220;mtd15 mtm15&#8243; font_size=&#8220;13px&#8220;]Mit 30-mm-Sockel, zentraler Arms\u00e4ule mit verstellbarer H\u00f6he von 650 mm bis 1050 mm, 4 drehbaren R\u00e4dern, 2 mit Bremsen.<br \/>\nGewicht 185 kg<br \/>\n(Niedrige R\u00e4der)[\/vc_column_text][\/vc_column][vc_column width=&#8220;1\/4&#8243; el_class=&#8220;mtm40&#8243;]<style>.vcex-image.vcex_6a57e67d06d7c .vcex-image-img{border-radius:0px;border-color:#00000042;}<\/style><figure class=\"vcex-image vcex-module wpex-text-center vcex_6a57e67d06d7c\"><div class=\"vcex-image-inner wpex-relative wpex-inline-block\"><a href=\"https:\/\/volumec.com\/wp-content\/uploads\/2025\/02\/ccm001-eam.jpg\" class=\"wpex-lightbox\"><img width=\"1128\" height=\"1128\" src=\"https:\/\/volumec.com\/wp-content\/uploads\/2025\/02\/ccm001-eam.jpg\" class=\"vcex-image-img wpex-align-middle wpex-border wpex-border-solid\" alt=\"\" loading=\"lazy\" decoding=\"async\" srcset=\"https:\/\/volumec.com\/wp-content\/uploads\/2025\/02\/ccm001-eam.jpg 1128w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/02\/ccm001-eam-300x300.jpg 300w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/02\/ccm001-eam-1024x1024.jpg 1024w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/02\/ccm001-eam-150x150.jpg 150w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/02\/ccm001-eam-768x768.jpg 768w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/02\/ccm001-eam-600x600.jpg 600w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/02\/ccm001-eam-100x100.jpg 100w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/02\/ccm001-eam-460x460.jpg 460w\" sizes=\"auto, (max-width: 1128px) 100vw, 1128px\" \/><\/a><\/div><\/figure>[vc_column_text css=&#8220;&#8220; font_size=&#8220;19px&#8220; line_height=&#8220;100%&#8220; font_weight=&#8220;700&#8243; el_class=&#8220;mtd20 mtm20&#8243;]\n<p class=\"mb-2\">(CCM001) WAGEN MIT SOCKEL 800X800X30 mm<\/p>\n[\/vc_column_text][vc_column_text css=&#8220;&#8220; el_class=&#8220;mtd15 mtm15&#8243; font_size=&#8220;13px&#8220;]Komplett mit Hubs\u00e4ulenarm h=2000 mm<br \/>\nBewegung auf Linearf\u00fchrung und Trapezstange mit elektrischem oder pneumatischem Schraubenzieher bet\u00e4tigt<br \/>\n4 drehbare R\u00e4der, 2 davon mit gebremstem Schiebegriff.<br \/>\nGewicht 220 Kg[\/vc_column_text][\/vc_column][vc_column width=&#8220;1\/4&#8243; el_class=&#8220;mtm40&#8243;]<style>.vcex-image.vcex_6a57e67d08a14 .vcex-image-img{border-radius:0px;border-color:#00000042;}<\/style><figure class=\"vcex-image vcex-module wpex-text-center vcex_6a57e67d08a14\"><div class=\"vcex-image-inner wpex-relative wpex-inline-block\"><a href=\"https:\/\/volumec.com\/wp-content\/uploads\/2025\/05\/CCM100-EAM.png\" class=\"wpex-lightbox\"><img width=\"800\" height=\"800\" src=\"https:\/\/volumec.com\/wp-content\/uploads\/2025\/05\/CCM100-EAM.png\" class=\"vcex-image-img wpex-align-middle wpex-border wpex-border-solid\" alt=\"\" loading=\"lazy\" decoding=\"async\" srcset=\"https:\/\/volumec.com\/wp-content\/uploads\/2025\/05\/CCM100-EAM.png 800w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/05\/CCM100-EAM-300x300.png 300w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/05\/CCM100-EAM-150x150.png 150w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/05\/CCM100-EAM-768x768.png 768w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/05\/CCM100-EAM-600x600.png 600w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/05\/CCM100-EAM-100x100.png 100w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/05\/CCM100-EAM-460x460.png 460w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/div><\/figure>[vc_column_text css=&#8220;&#8220; font_size=&#8220;19px&#8220; line_height=&#8220;100%&#8220; font_weight=&#8220;700&#8243; el_class=&#8220;mtd20 mtm20&#8243;]\n<p class=\"mb-2\">(CCM001-EAM) TROLLEY 800X800X30 mm<\/p>\n[\/vc_column_text][vc_column_text css=&#8220;&#8220; el_class=&#8220;mtd15 mtm15&#8243; font_size=&#8220;13px&#8220;]Komplett mit Hubs\u00e4ulenarm h=1920 mm<br \/>\nBewegung auf Linearf\u00fchrung und Trapezstange mit elektrischer oder pneumatischer Schraubendrehersteuerung Halterungen f\u00fcr 4 drehbare R\u00e4der, 2 mit Bremse<br \/>\nSchiebegriff.<br \/>\nGewicht 240 Kg<br \/>\n(Niedrige R\u00e4der)[\/vc_column_text][\/vc_column][vc_column width=&#8220;1\/4&#8243;]<style>.vcex-image.vcex_6a57e67d0a64a .vcex-image-img{border-radius:0px;border-color:#00000042;}<\/style><figure class=\"vcex-image vcex-module wpex-text-center vcex_6a57e67d0a64a\"><div class=\"vcex-image-inner wpex-relative wpex-inline-block\"><a href=\"https:\/\/volumec.com\/wp-content\/uploads\/2025\/02\/cf001.jpg\" class=\"wpex-lightbox\"><img width=\"800\" height=\"800\" src=\"https:\/\/volumec.com\/wp-content\/uploads\/2025\/02\/cf001.jpg\" class=\"vcex-image-img wpex-align-middle wpex-border wpex-border-solid\" alt=\"\" loading=\"lazy\" decoding=\"async\" srcset=\"https:\/\/volumec.com\/wp-content\/uploads\/2025\/02\/cf001.jpg 800w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/02\/cf001-300x300.jpg 300w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/02\/cf001-150x150.jpg 150w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/02\/cf001-768x768.jpg 768w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/02\/cf001-600x600.jpg 600w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/02\/cf001-100x100.jpg 100w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/02\/cf001-460x460.jpg 460w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/div><\/figure>[vc_column_text css=&#8220;&#8220; font_size=&#8220;19px&#8220; line_height=&#8220;100%&#8220; font_weight=&#8220;700&#8243; el_class=&#8220;mtd20 mtm20&#8243;](CF001) HUBS\u00c4ULENARMH=1850 mm[\/vc_column_text][vc_column_text css=&#8220;&#8220; el_class=&#8220;mtd15 mtm15&#8243; font_size=&#8220;13px&#8220;]Bewegung auf Linearf\u00fchrung und Trapezstange, gesteuert mit elektrischem oder pneumatischem Schraubenzieher.<br \/>\nGewicht 60 Kg[\/vc_column_text][\/vc_column][\/vc_row][vc_row full_width=&#8220;stretch_row&#8220; el_class=&#8220;ptd40 mtm40&#8243; css=&#8220;.vc_custom_1740932748828{padding-bottom: 50px !important;background-color: #F1F1F1 !important;}&#8220;][vc_column width=&#8220;1\/4&#8243; el_class=&#8220;mtm40&#8243;]<style>.vcex-image.vcex_6a57e67d0c2b5 .vcex-image-img{border-radius:0px;border-color:#00000042;}<\/style><figure class=\"vcex-image vcex-module wpex-text-center vcex_6a57e67d0c2b5\"><div class=\"vcex-image-inner wpex-relative wpex-inline-block\"><a href=\"https:\/\/volumec.com\/wp-content\/uploads\/2025\/05\/CS001-NEW.png\" class=\"wpex-lightbox\"><img width=\"1280\" height=\"1280\" src=\"https:\/\/volumec.com\/wp-content\/uploads\/2025\/05\/CS001-NEW.png\" class=\"vcex-image-img wpex-align-middle wpex-border wpex-border-solid\" alt=\"\" loading=\"lazy\" decoding=\"async\" srcset=\"https:\/\/volumec.com\/wp-content\/uploads\/2025\/05\/CS001-NEW.png 1280w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/05\/CS001-NEW-300x300.png 300w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/05\/CS001-NEW-1024x1024.png 1024w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/05\/CS001-NEW-150x150.png 150w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/05\/CS001-NEW-768x768.png 768w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/05\/CS001-NEW-600x600.png 600w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/05\/CS001-NEW-100x100.png 100w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/05\/CS001-NEW-460x460.png 460w\" sizes=\"auto, (max-width: 1280px) 100vw, 1280px\" \/><\/a><\/div><\/figure>[vc_column_text css=&#8220;&#8220; font_size=&#8220;19px&#8220; line_height=&#8220;100%&#8220; font_weight=&#8220;700&#8243; el_class=&#8220;mtd20 mtm20&#8243;]\n<p class=\"mb-2\">(CS001)\u00a0WAGEN MIT SOCKEL 800X800X30 mm<\/p>\n[\/vc_column_text][vc_column_text css=&#8220;&#8220; el_class=&#8220;mtd15 mtm15&#8243; font_size=&#8220;13px&#8220;]Bewegung auf 2 drehbaren R\u00e4dern mit Bremse, 2 festen, Schiebeb\u00fcgel.<br \/>\nGewicht 155 Kg.[\/vc_column_text][\/vc_column][vc_column width=&#8220;1\/4&#8243; el_class=&#8220;mtm40&#8243;]<style>.vcex-image.vcex_6a57e67d0deda .vcex-image-img{border-radius:0px;border-color:#00000042;}<\/style><figure class=\"vcex-image vcex-module wpex-text-center vcex_6a57e67d0deda\"><div class=\"vcex-image-inner wpex-relative wpex-inline-block\"><a href=\"https:\/\/volumec.com\/wp-content\/uploads\/2025\/02\/tds2000.jpg\" class=\"wpex-lightbox\"><img width=\"800\" height=\"800\" src=\"https:\/\/volumec.com\/wp-content\/uploads\/2025\/02\/tds2000.jpg\" class=\"vcex-image-img wpex-align-middle wpex-border wpex-border-solid\" alt=\"\" loading=\"lazy\" decoding=\"async\" srcset=\"https:\/\/volumec.com\/wp-content\/uploads\/2025\/02\/tds2000.jpg 800w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/02\/tds2000-300x300.jpg 300w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/02\/tds2000-150x150.jpg 150w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/02\/tds2000-768x768.jpg 768w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/02\/tds2000-600x600.jpg 600w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/02\/tds2000-100x100.jpg 100w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/02\/tds2000-460x460.jpg 460w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/div><\/figure>[vc_column_text css=&#8220;&#8220; font_size=&#8220;19px&#8220; line_height=&#8220;100%&#8220; font_weight=&#8220;700&#8243; el_class=&#8220;mtd20 mtm20&#8243;]\n<p class=\"mb-2\">(TDS2000) LINEARGLEITF\u00dcHRUNG<\/p>\n[\/vc_column_text][vc_column_text css=&#8220;&#8220; el_class=&#8220;mtd15 mtm15&#8243; font_size=&#8220;13px&#8220;]Gesamtl\u00e4nge 2200 mm<br \/>\nArbeitshub 2000 mm mit selbsttragender Struktur und 4 verstellbaren Auslegern.<br \/>\nGewicht: Kg.120[\/vc_column_text][\/vc_column][vc_column width=&#8220;1\/4&#8243;]<style>.vcex-image.vcex_6a57e67d0fb7c .vcex-image-img{border-radius:0px;border-color:#00000042;}<\/style><figure class=\"vcex-image vcex-module wpex-text-center vcex_6a57e67d0fb7c\"><div class=\"vcex-image-inner wpex-relative wpex-inline-block\"><a href=\"https:\/\/volumec.com\/wp-content\/uploads\/2025\/02\/kscea2.jpg\" class=\"wpex-lightbox\"><img width=\"800\" height=\"800\" src=\"https:\/\/volumec.com\/wp-content\/uploads\/2025\/02\/kscea2.jpg\" class=\"vcex-image-img wpex-align-middle wpex-border wpex-border-solid\" alt=\"\" loading=\"lazy\" decoding=\"async\" srcset=\"https:\/\/volumec.com\/wp-content\/uploads\/2025\/02\/kscea2.jpg 800w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/02\/kscea2-300x300.jpg 300w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/02\/kscea2-150x150.jpg 150w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/02\/kscea2-768x768.jpg 768w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/02\/kscea2-600x600.jpg 600w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/02\/kscea2-100x100.jpg 100w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/02\/kscea2-460x460.jpg 460w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/div><\/figure>[vc_column_text css=&#8220;&#8220; font_size=&#8220;19px&#8220; line_height=&#8220;100%&#8220; font_weight=&#8220;700&#8243; el_class=&#8220;mtd20 mtm20&#8243;](KSCEA3) KABELHALTERUNGSSATZ EA1-EAB1-EA2-EAB2[\/vc_column_text][vc_column_text css=&#8220;&#8220; el_class=&#8220;mtd15 mtm15&#8243; font_size=&#8220;13px&#8220;]\u00f8 MAX 29 mm[\/vc_column_text][\/vc_column][vc_column width=&#8220;1\/4&#8243;]<style>.vcex-image.vcex_6a57e67d117f2 .vcex-image-img{border-radius:0px;border-color:#00000042;}<\/style><figure class=\"vcex-image vcex-module wpex-text-center vcex_6a57e67d117f2\"><div class=\"vcex-image-inner wpex-relative wpex-inline-block\"><a href=\"https:\/\/volumec.com\/wp-content\/uploads\/2025\/02\/sfp120.jpg\" class=\"wpex-lightbox\"><img width=\"800\" height=\"800\" src=\"https:\/\/volumec.com\/wp-content\/uploads\/2025\/02\/sfp120.jpg\" class=\"vcex-image-img wpex-align-middle wpex-border wpex-border-solid\" alt=\"\" loading=\"lazy\" decoding=\"async\" srcset=\"https:\/\/volumec.com\/wp-content\/uploads\/2025\/02\/sfp120.jpg 800w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/02\/sfp120-300x300.jpg 300w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/02\/sfp120-150x150.jpg 150w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/02\/sfp120-768x768.jpg 768w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/02\/sfp120-600x600.jpg 600w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/02\/sfp120-100x100.jpg 100w, https:\/\/volumec.com\/wp-content\/uploads\/2025\/02\/sfp120-460x460.jpg 460w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/div><\/figure>[vc_column_text css=&#8220;&#8220; font_size=&#8220;19px&#8220; line_height=&#8220;100%&#8220; font_weight=&#8220;700&#8243; el_class=&#8220;mtd20 mtm20&#8243;]\n<p class=\"mb-2\">(SFP120) WANDHALTERUNG<\/p>\n[\/vc_column_text][vc_column_text css=&#8220;&#8220; el_class=&#8220;mtd15 mtm15&#8243; font_size=&#8220;13px&#8220;]Max. Gewicht 20 kg[\/vc_column_text][\/vc_column][\/vc_row][vc_row css_animation=&#8220;fadeIn&#8220; full_width=&#8220;stretch_row&#8220; content_placement=&#8220;middle&#8220; parallax=&#8220;content-moving&#8220; parallax_image=&#8220;277&#8243; el_class=&#8220;riga_banner ptd30 pbd30 ptm40 pbm40&#8243;][vc_column width=&#8220;1\/2&#8243;]<style>.vcex-image.vcex_6a57e67d1344b .vcex-image-inner{max-width:600px;}<\/style><figure class=\"vcex-image vcex-module vcex_6a57e67d1344b\"><div class=\"vcex-image-inner wpex-relative wpex-inline-block\"><img width=\"1000\" height=\"239\" src=\"https:\/\/volumec.com\/wp-content\/uploads\/2024\/12\/logo-Volumec.png\" class=\"vcex-image-img wpex-align-middle\" alt=\"\" loading=\"lazy\" decoding=\"async\" srcset=\"https:\/\/volumec.com\/wp-content\/uploads\/2024\/12\/logo-Volumec.png 1000w, https:\/\/volumec.com\/wp-content\/uploads\/2024\/12\/logo-Volumec-300x72.png 300w, https:\/\/volumec.com\/wp-content\/uploads\/2024\/12\/logo-Volumec-768x184.png 768w, https:\/\/volumec.com\/wp-content\/uploads\/2024\/12\/logo-Volumec-600x143.png 600w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/div><\/figure>[\/vc_column][vc_column width=&#8220;1\/2&#8243; el_class=&#8220;ptm40 cm&#8220;][vc_column_text css=&#8220;&#8220; color=&#8220;#ffffff&#8220; font_size=&#8220;d:100px|pl:45px|pp:45px&#8220; line_height=&#8220;110%&#8220; font_weight=&#8220;300&#8243;]Be <strong>innovative<\/strong>[\/vc_column_text][\/vc_column][\/vc_row]\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row full_width=&#8220;stretch_row&#8220; css=&#8220;.vc_custom_1741128533329{padding-top: 70px !important;padding-bottom: 70px !important;background: #13212E url(http:\/\/volumec.com\/wp-content\/uploads\/2024\/12\/Be-innovative.jpg?id=277) !important;}&#8220;][vc_column][vc_column_text css=&#8220;&#8220; text_align=&#8220;center&#8220; color=&#8220;#ffffff&#8220;] EASYARM 4 [\/vc_column_text][\/vc_column][\/vc_row][vc_row full_width=&#8220;stretch_row&#8220; el_class=&#8220;ptd80 pbd80 ptm40 pbm40&#8243;][vc_column width=&#8220;1\/2&#8243;][vc_column_text css=&#8220;&#8220; text_transform=&#8220;uppercase&#8220;] Ausbalanciertes Gelenkarm-System [\/vc_column_text][vc_column_text css=&#8220;&#8220; el_class=&#8220;mtd50 mtm40 mbd40 mbm30&#8243;]Die Baureihe EasyArm wurde konzipiert um Werkzeuge oder sonstige Apparate, bis zu einem max. Gewicht von 30 kg, aufzunehmen. Der Aufbau dieses Systems, komplett&hellip;<\/p>\n","protected":false},"author":3,"featured_media":0,"parent":464,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"class_list":["post-3864","page","type-page","status-publish","hentry","entry","no-media"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>EASYARM 4 - Volumec<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/volumec.com\/de\/ausbalanciertes-gelenkarm-system\/easyarm-4\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"EASYARM 4 - Volumec\" \/>\n<meta property=\"og:description\" content=\"[vc_row full_width=&#8220;stretch_row&#8220; css=&#8220;.vc_custom_1741128533329{padding-top: 70px !important;padding-bottom: 70px !important;background: #13212E url(http:\/\/volumec.com\/wp-content\/uploads\/2024\/12\/Be-innovative.jpg?id=277) !important;}&#8220;][vc_column][vc_column_text css=&#8220;&#8220; text_align=&#8220;center&#8220; color=&#8220;#ffffff&#8220;] EASYARM 4 [\/vc_column_text][\/vc_column][\/vc_row][vc_row full_width=&#8220;stretch_row&#8220; el_class=&#8220;ptd80 pbd80 ptm40 pbm40&#8243;][vc_column width=&#8220;1\/2&#8243;][vc_column_text css=&#8220;&#8220; text_transform=&#8220;uppercase&#8220;] Ausbalanciertes Gelenkarm-System [\/vc_column_text][vc_column_text css=&#8220;&#8220; el_class=&#8220;mtd50 mtm40 mbd40 mbm30&#8243;]Die Baureihe EasyArm wurde konzipiert um Werkzeuge oder sonstige Apparate, bis zu einem max. Gewicht von 30 kg, aufzunehmen. Der Aufbau dieses Systems, komplett&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/volumec.com\/de\/ausbalanciertes-gelenkarm-system\/easyarm-4\/\" \/>\n<meta property=\"og:site_name\" content=\"Volumec\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-27T11:57:34+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"20\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/volumec.com\/de\/ausbalanciertes-gelenkarm-system\/easyarm-4\/\",\"url\":\"https:\/\/volumec.com\/de\/ausbalanciertes-gelenkarm-system\/easyarm-4\/\",\"name\":\"EASYARM 4 - Volumec\",\"isPartOf\":{\"@id\":\"https:\/\/www.volumec.com\/en\/#website\"},\"datePublished\":\"2025-02-19T15:46:37+00:00\",\"dateModified\":\"2025-10-27T11:57:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/volumec.com\/de\/ausbalanciertes-gelenkarm-system\/easyarm-4\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/volumec.com\/de\/ausbalanciertes-gelenkarm-system\/easyarm-4\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/volumec.com\/de\/ausbalanciertes-gelenkarm-system\/easyarm-4\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/volumec.com\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ausbalanciertes Gelenkarm System\",\"item\":\"https:\/\/volumec.com\/de\/ausbalanciertes-gelenkarm-system\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"EASYARM 4\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.volumec.com\/en\/#website\",\"url\":\"https:\/\/www.volumec.com\/en\/\",\"name\":\"Volumec.com\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.volumec.com\/en\/#organization\"},\"alternateName\":\"be innovative\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.volumec.com\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.volumec.com\/en\/#organization\",\"name\":\"Volumec\",\"url\":\"https:\/\/www.volumec.com\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.volumec.com\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/volumec.com\/wp-content\/uploads\/2024\/12\/Volumec-logo.png\",\"contentUrl\":\"https:\/\/volumec.com\/wp-content\/uploads\/2024\/12\/Volumec-logo.png\",\"width\":320,\"height\":77,\"caption\":\"Volumec\"},\"image\":{\"@id\":\"https:\/\/www.volumec.com\/en\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"EASYARM 4 - Volumec","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/volumec.com\/de\/ausbalanciertes-gelenkarm-system\/easyarm-4\/","og_locale":"de_DE","og_type":"article","og_title":"EASYARM 4 - Volumec","og_description":"[vc_row full_width=&#8220;stretch_row&#8220; css=&#8220;.vc_custom_1741128533329{padding-top: 70px !important;padding-bottom: 70px !important;background: #13212E url(http:\/\/volumec.com\/wp-content\/uploads\/2024\/12\/Be-innovative.jpg?id=277) !important;}&#8220;][vc_column][vc_column_text css=&#8220;&#8220; text_align=&#8220;center&#8220; color=&#8220;#ffffff&#8220;] EASYARM 4 [\/vc_column_text][\/vc_column][\/vc_row][vc_row full_width=&#8220;stretch_row&#8220; el_class=&#8220;ptd80 pbd80 ptm40 pbm40&#8243;][vc_column width=&#8220;1\/2&#8243;][vc_column_text css=&#8220;&#8220; text_transform=&#8220;uppercase&#8220;] Ausbalanciertes Gelenkarm-System [\/vc_column_text][vc_column_text css=&#8220;&#8220; el_class=&#8220;mtd50 mtm40 mbd40 mbm30&#8243;]Die Baureihe EasyArm wurde konzipiert um Werkzeuge oder sonstige Apparate, bis zu einem max. Gewicht von 30 kg, aufzunehmen. Der Aufbau dieses Systems, komplett&hellip;","og_url":"https:\/\/volumec.com\/de\/ausbalanciertes-gelenkarm-system\/easyarm-4\/","og_site_name":"Volumec","article_modified_time":"2025-10-27T11:57:34+00:00","twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"20\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/volumec.com\/de\/ausbalanciertes-gelenkarm-system\/easyarm-4\/","url":"https:\/\/volumec.com\/de\/ausbalanciertes-gelenkarm-system\/easyarm-4\/","name":"EASYARM 4 - Volumec","isPartOf":{"@id":"https:\/\/www.volumec.com\/en\/#website"},"datePublished":"2025-02-19T15:46:37+00:00","dateModified":"2025-10-27T11:57:34+00:00","breadcrumb":{"@id":"https:\/\/volumec.com\/de\/ausbalanciertes-gelenkarm-system\/easyarm-4\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/volumec.com\/de\/ausbalanciertes-gelenkarm-system\/easyarm-4\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/volumec.com\/de\/ausbalanciertes-gelenkarm-system\/easyarm-4\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/volumec.com\/de\/"},{"@type":"ListItem","position":2,"name":"Ausbalanciertes Gelenkarm System","item":"https:\/\/volumec.com\/de\/ausbalanciertes-gelenkarm-system\/"},{"@type":"ListItem","position":3,"name":"EASYARM 4"}]},{"@type":"WebSite","@id":"https:\/\/www.volumec.com\/en\/#website","url":"https:\/\/www.volumec.com\/en\/","name":"Volumec.com","description":"","publisher":{"@id":"https:\/\/www.volumec.com\/en\/#organization"},"alternateName":"be innovative","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.volumec.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.volumec.com\/en\/#organization","name":"Volumec","url":"https:\/\/www.volumec.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.volumec.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/volumec.com\/wp-content\/uploads\/2024\/12\/Volumec-logo.png","contentUrl":"https:\/\/volumec.com\/wp-content\/uploads\/2024\/12\/Volumec-logo.png","width":320,"height":77,"caption":"Volumec"},"image":{"@id":"https:\/\/www.volumec.com\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/volumec.com\/de\/wp-json\/wp\/v2\/pages\/3864","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/volumec.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/volumec.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/volumec.com\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/volumec.com\/de\/wp-json\/wp\/v2\/comments?post=3864"}],"version-history":[{"count":12,"href":"https:\/\/volumec.com\/de\/wp-json\/wp\/v2\/pages\/3864\/revisions"}],"predecessor-version":[{"id":9503,"href":"https:\/\/volumec.com\/de\/wp-json\/wp\/v2\/pages\/3864\/revisions\/9503"}],"up":[{"embeddable":true,"href":"https:\/\/volumec.com\/de\/wp-json\/wp\/v2\/pages\/464"}],"wp:attachment":[{"href":"https:\/\/volumec.com\/de\/wp-json\/wp\/v2\/media?parent=3864"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}